{"id":27,"date":"2024-01-15T21:22:32","date_gmt":"2024-01-15T21:22:32","guid":{"rendered":"https:\/\/labs.100x100.net\/projects\/velaclassica\/?page_id=27"},"modified":"2026-07-09T11:20:31","modified_gmt":"2026-07-09T11:20:31","slug":"prensa","status":"publish","type":"page","link":"https:\/\/puigvelaclassica.com\/es\/prensa\/","title":{"rendered":"Prensa"},"content":{"rendered":"<h2>Departamento de prensa<\/h2>\n<p><a href=\"mailto:puigvelaclassica@comunicacionrrpp.es\">puigvelaclassica@comunicacionrrpp.es<\/a><\/p>\n<p><a href=\"mailto:cmunoz@comunicacionrrpp.es\">Covadonga Mu\u00f1oz<\/a> (602 226 701)<\/p>\n<p class=\"botonespress\"><a class=\"calltoaction\" href=\"https:\/\/www.puigvelaclassica.com\/es\/noticias\/\">VER NOTAS DE PRENSA<\/a><br \/>\n<a class=\"calltoaction\" href=\"https:\/\/www.puigvelaclassica.com\/es\/actualidad-videos\/\">\u00daLTIMOS V\u00cdDEOS<\/a><br \/>\n<a class=\"calltoaction\" href=\"https:\/\/www.puigvelaclassica.com\/es\/fotos-de-alta-calidad\/\">FOTOS DE ALTA CALIDAD<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Departamento de prensa puigvelaclassica@comunicacionrrpp.es Covadonga Mu\u00f1oz (602 226 701) VER NOTAS DE PRENSA \u00daLTIMOS V\u00cdDEOS FOTOS DE ALTA CALIDAD<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-centered.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-27","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Prensa - Puig Vela Cl\u00e0ssica Barcelona<\/title>\n<meta name=\"description\" content=\"Para cualquier consulta adicional de prensa y medios de la regata Puig Vela Cl\u00e0ssica Barcelona, comun\u00edquese con nuestra oficina de prensa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/puigvelaclassica.com\/es\/prensa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prensa - Puig Vela Cl\u00e0ssica Barcelona\" \/>\n<meta property=\"og:description\" content=\"Para cualquier consulta adicional de prensa y medios de la regata Puig Vela Cl\u00e0ssica Barcelona, comun\u00edquese con nuestra oficina de prensa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/puigvelaclassica.com\/es\/prensa\/\" \/>\n<meta property=\"og:site_name\" content=\"Puig Vela Cl\u00e0ssica Barcelona\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-09T11:20:31+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/puigvelaclassica.com\/es\/prensa\/\",\"url\":\"https:\/\/puigvelaclassica.com\/es\/prensa\/\",\"name\":\"Prensa - Puig Vela Cl\u00e0ssica Barcelona\",\"isPartOf\":{\"@id\":\"https:\/\/www.puigvelaclassica.com\/es\/#website\"},\"datePublished\":\"2024-01-15T21:22:32+00:00\",\"dateModified\":\"2026-07-09T11:20:31+00:00\",\"description\":\"Para cualquier consulta adicional de prensa y medios de la regata Puig Vela Cl\u00e0ssica Barcelona, comun\u00edquese con nuestra oficina de prensa.\",\"breadcrumb\":{\"@id\":\"https:\/\/puigvelaclassica.com\/es\/prensa\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/puigvelaclassica.com\/es\/prensa\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/puigvelaclassica.com\/es\/prensa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.puigvelaclassica.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prensa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.puigvelaclassica.com\/es\/#website\",\"url\":\"https:\/\/www.puigvelaclassica.com\/es\/\",\"name\":\"Puig Vela Cl\u00e0ssica Barcelona\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.puigvelaclassica.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prensa - Puig Vela Cl\u00e0ssica Barcelona","description":"Para cualquier consulta adicional de prensa y medios de la regata Puig Vela Cl\u00e0ssica Barcelona, comun\u00edquese con nuestra oficina de prensa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/puigvelaclassica.com\/es\/prensa\/","og_locale":"es_ES","og_type":"article","og_title":"Prensa - Puig Vela Cl\u00e0ssica Barcelona","og_description":"Para cualquier consulta adicional de prensa y medios de la regata Puig Vela Cl\u00e0ssica Barcelona, comun\u00edquese con nuestra oficina de prensa.","og_url":"https:\/\/puigvelaclassica.com\/es\/prensa\/","og_site_name":"Puig Vela Cl\u00e0ssica Barcelona","article_modified_time":"2026-07-09T11:20:31+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/puigvelaclassica.com\/es\/prensa\/","url":"https:\/\/puigvelaclassica.com\/es\/prensa\/","name":"Prensa - Puig Vela Cl\u00e0ssica Barcelona","isPartOf":{"@id":"https:\/\/www.puigvelaclassica.com\/es\/#website"},"datePublished":"2024-01-15T21:22:32+00:00","dateModified":"2026-07-09T11:20:31+00:00","description":"Para cualquier consulta adicional de prensa y medios de la regata Puig Vela Cl\u00e0ssica Barcelona, comun\u00edquese con nuestra oficina de prensa.","breadcrumb":{"@id":"https:\/\/puigvelaclassica.com\/es\/prensa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/puigvelaclassica.com\/es\/prensa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/puigvelaclassica.com\/es\/prensa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.puigvelaclassica.com\/es\/"},{"@type":"ListItem","position":2,"name":"Prensa"}]},{"@type":"WebSite","@id":"https:\/\/www.puigvelaclassica.com\/es\/#website","url":"https:\/\/www.puigvelaclassica.com\/es\/","name":"Puig Vela Cl\u00e0ssica Barcelona","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.puigvelaclassica.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/pages\/27","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/comments?post=27"}],"version-history":[{"count":8,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/pages\/27\/revisions"}],"predecessor-version":[{"id":8784,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/pages\/27\/revisions\/8784"}],"wp:attachment":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/media?parent=27"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}