{"id":1649,"date":"2012-07-13T17:22:41","date_gmt":"2012-07-13T17:22:41","guid":{"rendered":"http:\/\/www.puigvelaclassica.com\/?p=1649"},"modified":"2024-01-21T21:53:39","modified_gmt":"2024-01-21T21:53:39","slug":"competicion-al-rojo-vivo-en-la-segunda-jornada-de-la-regata-puig-vela-classica-barcelona-2","status":"publish","type":"post","link":"https:\/\/puigvelaclassica.com\/es\/competicion-al-rojo-vivo-en-la-segunda-jornada-de-la-regata-puig-vela-classica-barcelona-2\/","title":{"rendered":"Competici\u00f3n al rojo vivo en la segunda jornada de la Regata Puig Vela Cl\u00e0ssica Barcelona"},"content":{"rendered":"<ul>\n<li>La salida de la jornada, que ha tenido lugar hoy frente al Puerto Ol\u00edmpico de Barcelona, ha sido muy t\u00e9cnica y espectacular gracias a los emocionantes duelos de esta flota tan competitiva<\/li>\n<li>Cada uno de los veleros es una pieza hist\u00f3rica  que patrones y tripulaci\u00f3n cuidan con esmero para mantener su esp\u00edritu original<\/li>\n<\/ul>\n<p>El Puerto Ol\u00edmpico de Barcelona ha sido el escenario que ha acogido la salida de la segunda jornada de la Regata Puig Vela Cl\u00e0ssica Barcelona. Los veleros han navegado muy cerca de la costa hasta la altura del Hotel Wela, de manera que el p\u00fablico desde la costa de la ciudad ha podido disfrutar, un d\u00eda m\u00e1s, de este espect\u00e1culo \u00fanico de joyas n\u00e1uticas.<\/p>\n<p>Uno de los principales atractivos de la regata es que, por las propias caracter\u00edsticas de la competici\u00f3n, los veleros navegan muy juntos, lo que hace posible a las tripulaciones contemplar muy de cerca las maniobras de navegaci\u00f3n de sus competidores y hacer m\u00e1s re\u00f1ida la regata.<\/p>\n<h1>El m\u00e1s peque\u00f1o el protagonista de la jornada<\/h1>\n<p>La segunda jornada de la regata Puig Vela Cl\u00e1ssica Barcelona ha tenido en el viento de Garb\u00ed un destacado protagonista. Un cl\u00e1sico estival que con su intensidad de 14-18 nudos ha vestido con sus mejores galas el campo de regatas barcelon\u00e9s.<\/p>\n<p>Ante tan buen regalo meteorol\u00f3gico, el Comit\u00e9 de Regatas no da dudado un segundo en organizar puntualmente un recorrido costero, que ha totalizado 18,5 millas (33 km) y transcurrido por cinco tramos de rumbos variados, si bien hoy los trayectos m\u00e1s t\u00e9cnicos de ce\u00f1ida han cobrado mayor protagonismo que ayer.<\/p>\n<p>De nuevo ha sido la flota de Big Boats la encargada de iniciar la jornada, ofreciendo el Moonbeam III y el Thendara un emocionante cruce tras la salida, resuelto a favor del primero, que pudo comenzar su escapada, mientras el Moonbeam IV quedaba levemente rezagado y a\u00f1ad\u00eda trapo a su imponente aparejo para poder rebasar a su \u201chermano peque\u00f1o\u201d poco antes de completar la mitad del recorrido. No obstante, tras finalizar la prueba y aplicar el h\u00e1ndicap de tiempos acordes a los distintos tama\u00f1os, el Moonbeam III sac\u00f3 partido de sus impecables maniobras y estrategia en las ce\u00f1idas, anot\u00e1ndose la prueba, seguido por el Moonbeam IV y el Thendara. Tras una revisi\u00f3n de las clasificaciones de ayer, en las que finalmente se ha establecido el mismo orden que hoy, el Moonbeam III lidera la categor\u00eda a falta de la prueba final que ma\u00f1ana dilucidar\u00e1 la categor\u00eda Big Boats.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2012\/07\/VPuigClassica_NM120713_4846-570x375-1.jpeg\" alt=\"\" title=\"Photo \u00a9MartinezStudio.es\" width=\"570\" height=\"375\" class=\"alignnone size-medium wp-image-717\" \/><\/p>\n<p>De gran m\u00e9rito ha sido la victoria del Silva Racing de Gon\u00e7alo Duarte Silva en la categor\u00eda de Cl\u00e1sicos. Se trata de un peque\u00f1o barco de 7,68 metros de eslora cuyo reducido tama\u00f1o endurece sus condiciones de navegaci\u00f3n con estos vientos, y cuyo menor velocidad alarga su tiempo real de regata. No obstante, el buen hacer de sus tres esforzados tripulantes les ha permitido superar al Alba tras la compensaci\u00f3n de tiempos. Pese a ceder el triunfo parcial, el Alba ha podido controlar al brit\u00e1nico Outlaw. Tras ellos, el Argos  completa la n\u00f3mina de favoritos para la victoria final de la Puig Vela Cl\u00e0ssica Barcelona, toda vez que el Diana fue quinto acusando la falta de una vela apropiada para estas ce\u00f1idas y alej\u00e1ndose del cuarteto de m\u00e1ximos aspirantes.<\/p>\n<p>M\u00e1s ajustada que ayer ha sido la victoria del Malabar X en la categor\u00eda Marconi Cangreja, donde el Avel ha demostrado su potencial y ha visto como su desventaja se reduc\u00eda considerablemente respecto a la prueba disputada ayer. De nuevo el Kelpie ha sido tercero, mientras el Gipsy ha podido competir tras resolver la aver\u00eda que ayer se lo impidiera. Los dos primeros puestos parciales que acumula el Malabar X le permiten acariciar el trofeo que recompensa al mejor Cangeja Marconi en esta Puig Vela Cla\u00e0ssica Barcelona, pero la perseverancia del Avel no le dejar\u00e1 bajar la guardia.<\/p>\n<p>M\u00e1s claro parece el desenlace en \u00c9poca Marconi, donde de nuevo el Manitou ha dado una lecci\u00f3n en el campo de regatas. Sin abusar de velas grandes, ha logrado navegar con el barco muy bien amarinado para ir distanci\u00e1ndose de sus rivales. Esta vez, el segundo puesto ha sido para el Argyll, que ayer concluy\u00f3 s\u00e9ptimo, mientras el Amarita ha repetido en la tercera plaza. El Cometa, que ayer fue segundo, ha sumado hoy un quinto puesto, que le deja tercero en la clasificaci\u00f3n a un punto del Amarita, previ\u00e9ndose un intenso duelo por la segunda plaza y a la espera de un posible error del Manitou que le impida ganar en \u00c9poca Marconi.<\/p>\n<p><a href=\"http:\/\/www.puigvelaclassica.com\/resultados\/\" title=\"Classificacions\">Resultados y clasificaciones al t\u00e9rmino de la segunda jornada<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La flota de barcos cl\u00e1sicos en Barcelona<\/p>\n","protected":false},"author":1,"featured_media":7602,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"class_list":["post-1649","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Competici\u00f3n al rojo vivo en la segunda jornada de la Regata Puig Vela Cl\u00e0ssica Barcelona - Puig Vela Cl\u00e0ssica Barcelona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/puigvelaclassica.com\/es\/competicion-al-rojo-vivo-en-la-segunda-jornada-de-la-regata-puig-vela-classica-barcelona-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Competici\u00f3n al rojo vivo en la segunda jornada de la Regata Puig Vela Cl\u00e0ssica Barcelona - Puig Vela Cl\u00e0ssica Barcelona\" \/>\n<meta property=\"og:description\" content=\"La flota de barcos cl\u00e1sicos en Barcelona\" \/>\n<meta property=\"og:url\" content=\"https:\/\/puigvelaclassica.com\/es\/competicion-al-rojo-vivo-en-la-segunda-jornada-de-la-regata-puig-vela-classica-barcelona-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Puig Vela Cl\u00e0ssica Barcelona\" \/>\n<meta property=\"article:published_time\" content=\"2012-07-13T17:22:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-21T21:53:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2012\/07\/4694.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1490\" \/>\n\t<meta property=\"og:image:height\" content=\"743\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"velaclassica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"velaclassica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/puigvelaclassica.com\/es\/competicion-al-rojo-vivo-en-la-segunda-jornada-de-la-regata-puig-vela-classica-barcelona-2\/\",\"url\":\"https:\/\/puigvelaclassica.com\/es\/competicion-al-rojo-vivo-en-la-segunda-jornada-de-la-regata-puig-vela-classica-barcelona-2\/\",\"name\":\"Competici\u00f3n al rojo vivo en la segunda jornada de la Regata Puig Vela Cl\u00e0ssica Barcelona - Puig Vela Cl\u00e0ssica Barcelona\",\"isPartOf\":{\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/puigvelaclassica.com\/es\/competicion-al-rojo-vivo-en-la-segunda-jornada-de-la-regata-puig-vela-classica-barcelona-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/puigvelaclassica.com\/es\/competicion-al-rojo-vivo-en-la-segunda-jornada-de-la-regata-puig-vela-classica-barcelona-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2012\/07\/4694.jpeg\",\"datePublished\":\"2012-07-13T17:22:41+00:00\",\"dateModified\":\"2024-01-21T21:53:39+00:00\",\"author\":{\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/0f1f6cd6f23050a19e91a3003de34c7e\"},\"breadcrumb\":{\"@id\":\"https:\/\/puigvelaclassica.com\/es\/competicion-al-rojo-vivo-en-la-segunda-jornada-de-la-regata-puig-vela-classica-barcelona-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/puigvelaclassica.com\/es\/competicion-al-rojo-vivo-en-la-segunda-jornada-de-la-regata-puig-vela-classica-barcelona-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/puigvelaclassica.com\/es\/competicion-al-rojo-vivo-en-la-segunda-jornada-de-la-regata-puig-vela-classica-barcelona-2\/#primaryimage\",\"url\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2012\/07\/4694.jpeg\",\"contentUrl\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2012\/07\/4694.jpeg\",\"width\":1490,\"height\":743},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/puigvelaclassica.com\/es\/competicion-al-rojo-vivo-en-la-segunda-jornada-de-la-regata-puig-vela-classica-barcelona-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mail.puigvelaclasica.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Competici\u00f3n al rojo vivo en la segunda jornada de la Regata Puig Vela Cl\u00e0ssica Barcelona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#website\",\"url\":\"https:\/\/www.puigvelaclassicabarcelona.com\/\",\"name\":\"Puig Vela Cl\u00e0ssica Barcelona\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.puigvelaclassicabarcelona.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/0f1f6cd6f23050a19e91a3003de34c7e\",\"name\":\"velaclassica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/18a97ff0e5d67038bad233b79246a7f922424d224871d207487c88e471e664c2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/18a97ff0e5d67038bad233b79246a7f922424d224871d207487c88e471e664c2?s=96&d=mm&r=g\",\"caption\":\"velaclassica\"},\"sameAs\":[\"https:\/\/puigvelaclassica.com\/\"],\"url\":\"https:\/\/puigvelaclassica.com\/es\/author\/velaclassica\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Competici\u00f3n al rojo vivo en la segunda jornada de la Regata Puig Vela Cl\u00e0ssica Barcelona - Puig Vela Cl\u00e0ssica Barcelona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/puigvelaclassica.com\/es\/competicion-al-rojo-vivo-en-la-segunda-jornada-de-la-regata-puig-vela-classica-barcelona-2\/","og_locale":"es_ES","og_type":"article","og_title":"Competici\u00f3n al rojo vivo en la segunda jornada de la Regata Puig Vela Cl\u00e0ssica Barcelona - Puig Vela Cl\u00e0ssica Barcelona","og_description":"La flota de barcos cl\u00e1sicos en Barcelona","og_url":"https:\/\/puigvelaclassica.com\/es\/competicion-al-rojo-vivo-en-la-segunda-jornada-de-la-regata-puig-vela-classica-barcelona-2\/","og_site_name":"Puig Vela Cl\u00e0ssica Barcelona","article_published_time":"2012-07-13T17:22:41+00:00","article_modified_time":"2024-01-21T21:53:39+00:00","og_image":[{"width":1490,"height":743,"url":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2012\/07\/4694.jpeg","type":"image\/jpeg"}],"author":"velaclassica","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"velaclassica","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/puigvelaclassica.com\/es\/competicion-al-rojo-vivo-en-la-segunda-jornada-de-la-regata-puig-vela-classica-barcelona-2\/","url":"https:\/\/puigvelaclassica.com\/es\/competicion-al-rojo-vivo-en-la-segunda-jornada-de-la-regata-puig-vela-classica-barcelona-2\/","name":"Competici\u00f3n al rojo vivo en la segunda jornada de la Regata Puig Vela Cl\u00e0ssica Barcelona - Puig Vela Cl\u00e0ssica Barcelona","isPartOf":{"@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/puigvelaclassica.com\/es\/competicion-al-rojo-vivo-en-la-segunda-jornada-de-la-regata-puig-vela-classica-barcelona-2\/#primaryimage"},"image":{"@id":"https:\/\/puigvelaclassica.com\/es\/competicion-al-rojo-vivo-en-la-segunda-jornada-de-la-regata-puig-vela-classica-barcelona-2\/#primaryimage"},"thumbnailUrl":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2012\/07\/4694.jpeg","datePublished":"2012-07-13T17:22:41+00:00","dateModified":"2024-01-21T21:53:39+00:00","author":{"@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/0f1f6cd6f23050a19e91a3003de34c7e"},"breadcrumb":{"@id":"https:\/\/puigvelaclassica.com\/es\/competicion-al-rojo-vivo-en-la-segunda-jornada-de-la-regata-puig-vela-classica-barcelona-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/puigvelaclassica.com\/es\/competicion-al-rojo-vivo-en-la-segunda-jornada-de-la-regata-puig-vela-classica-barcelona-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/puigvelaclassica.com\/es\/competicion-al-rojo-vivo-en-la-segunda-jornada-de-la-regata-puig-vela-classica-barcelona-2\/#primaryimage","url":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2012\/07\/4694.jpeg","contentUrl":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2012\/07\/4694.jpeg","width":1490,"height":743},{"@type":"BreadcrumbList","@id":"https:\/\/puigvelaclassica.com\/es\/competicion-al-rojo-vivo-en-la-segunda-jornada-de-la-regata-puig-vela-classica-barcelona-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mail.puigvelaclasica.com\/es\/"},{"@type":"ListItem","position":2,"name":"Competici\u00f3n al rojo vivo en la segunda jornada de la Regata Puig Vela Cl\u00e0ssica Barcelona"}]},{"@type":"WebSite","@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#website","url":"https:\/\/www.puigvelaclassicabarcelona.com\/","name":"Puig Vela Cl\u00e0ssica Barcelona","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.puigvelaclassicabarcelona.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/0f1f6cd6f23050a19e91a3003de34c7e","name":"velaclassica","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/18a97ff0e5d67038bad233b79246a7f922424d224871d207487c88e471e664c2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/18a97ff0e5d67038bad233b79246a7f922424d224871d207487c88e471e664c2?s=96&d=mm&r=g","caption":"velaclassica"},"sameAs":["https:\/\/puigvelaclassica.com\/"],"url":"https:\/\/puigvelaclassica.com\/es\/author\/velaclassica\/"}]}},"_links":{"self":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/posts\/1649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/comments?post=1649"}],"version-history":[{"count":1,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/posts\/1649\/revisions"}],"predecessor-version":[{"id":7607,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/posts\/1649\/revisions\/7607"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/media\/7602"}],"wp:attachment":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/media?parent=1649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/categories?post=1649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}