{"id":1670,"date":"2012-07-09T13:13:45","date_gmt":"2012-07-09T13:13:45","guid":{"rendered":"http:\/\/www.puigvelaclassica.com\/?p=1670"},"modified":"2024-01-21T22:00:16","modified_gmt":"2024-01-21T22:00:16","slug":"la-regata-puig-vela-classica-convierte-un-ano-mas-a-barcelona-en-la-capital-nautica-del-mediterraneo-2","status":"publish","type":"post","link":"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-convierte-un-ano-mas-a-barcelona-en-la-capital-nautica-del-mediterraneo-2\/","title":{"rendered":"La regata Puig Vela Cl\u00e0ssica convierte, un a\u00f1o m\u00e1s, a Barcelona en la capital n\u00e1utica del Mediterr\u00e1neo"},"content":{"rendered":"<ul>\n<li>La competici\u00f3n, que tendr\u00e1 lugar del 11 al 14 de julio, se consolida como el evento del a\u00f1o para los amantes de la navegaci\u00f3n cl\u00e1sica\n<li>\n<li>Medio centenar de embarcaciones internacionales de leyenda, procedentes de 10 pa\u00edses diferentes, desplegar\u00e1n sus velas en las aguas de la capital catalana\n<li>Debido al prestigio que ha ido ganando la regata a lo largo de sus cuatro ediciones, la organizaci\u00f3n ha logrado un acuerdo con el Servei Meteorologic de Catalunya\n<\/ul>\n<p>A menos de una semana de su celebraci\u00f3n, Barcelona ya est\u00e1 preparada para acoger una de las citas m\u00e1s c\u00e9lebres y esperadas de esta temporada: la Puig Vela Cl\u00e0ssica, que reunir\u00e1 a lo m\u00e1s destacado del mundo de la n\u00e1utica cl\u00e1sica. La quinta edici\u00f3n de la regata congregar\u00e1, entre el 11 y el 14 de julio, a los mejores veleros de todo el Mediterr\u00e1neo y convertir\u00e1 a Barcelona en un lugar de visita obligada para los amantes del mar.<\/p>\n<p>Medio centenar de leyendas n\u00e1uticas de nuestro pa\u00eds y de otros rincones del mundo como Francia, Inglaterra, Italia, Malta, Suecia, Alemania, Irlanda, Bahamas, Estados Unidos y Canad\u00e1 navegar\u00e1n hasta la capital catalana para ser part\u00edcipes de este espect\u00e1culo, que a\u00f1o tras a\u00f1o, va ganando protagonismo nacional e internacionalmente. De hecho, seg\u00fan estimaciones de la organizaci\u00f3n, m\u00e1s de 1.200 personas \u2013entre regatistas y acompa\u00f1antes\u2013 participar\u00e1n en este acontecimiento tan esperado para barceloneses y visitantes.<\/p>\n<p>Adem\u00e1s de la presencia de ganadores de la cuarta edici\u00f3n como The Blue Peter, Malabar X, Argos o Moonbeam III, este a\u00f1o la ciudad disfrutar\u00e1 de piezas n\u00e1uticas que desde el siglo XIX han forjado la tradici\u00f3n de la vela deportiva. El Creole, considerado uno de los veleros m\u00e1s bellos del mundo, de 65 metros de eslora; el Moonbeam IV, embarcaci\u00f3n en la que Rainiero de M\u00f3naco y Grace Kelly celebraron su luna de miel; o el Malabar X, uno de los barcos m\u00e1s importantes de la historia del dise\u00f1o de recreo, son algunas de las exclusivas embarcaciones que siguen vivas y est\u00e1n a punto de desplegar sus velas en el mar de Barcelona.<br \/>\n<img decoding=\"async\" src=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2012\/07\/V-Edicio\u0301n-Puig-Vela-Cla\u0300ssica-Barcelona-2.jpeg\" alt=\"\" title=\"IV PUIG CLASSICA, 15 07 2011\"  class=\"alignnone size-medium wp-image-565\" \/><\/p>\n<h1>Acuerdo con el Servei Meteorol\u00f2gic de Catalunya <\/h1>\n<p>Gracias al prestigio y al reconocimiento que ha ido ganando la regata a lo largo de sus cuatro ediciones, este a\u00f1o ha logrado contar con el apoyo del Servei Meteorol\u00f2gic de Catalunya, que ofrecer\u00e1 cada ma\u00f1ana asesoramiento metereol\u00f3gico en el Real Club N\u00e1utico de Barcelona. El 12 de julio por la ma\u00f1ana se ofrecer\u00e1 a los patrones de las embarcaciones participantes un briefing con informaci\u00f3n detallada sobre la evoluci\u00f3n del viento para cada uno de los tres d\u00edas que dura la regata. Por otro lado, antes de salir a navegar, los armadores, patrones y toda la tripulaci\u00f3n, recibir\u00e1n un detallado informe meteorol\u00f3gico diario. Asimismo, en su web oficial (www.meteo.cat) estar\u00e1 disponible un meteorograma que ofrecer\u00e1, en tiempo real, las previsiones detalladas, hora a hora, en la zona concreta en la que se disputar\u00e1 la competici\u00f3n.<br \/>\nPor primera vez, este a\u00f1o, todos los participantes de la regata recibir\u00e1n una medalla conmemorativa para fijar en la cubierta de sus embarcaciones a modo de recuerdo de la quinta edici\u00f3n de la Puig Vela Cl\u00e0ssica. Se trata una muestra de agradecimiento y reconocimiento a todos los armadores, patrones, y a la tripulaci\u00f3n que \u2013gracias a sus maravillosos barcos, a su esfuerzo, y al excelente trabajo en equipo que realizan\u2013 hacen que la Puig Vela Cl\u00e0ssica se supere a s\u00ed misma edici\u00f3n tras edici\u00f3n.<\/p>\n<h1>Un espect\u00e1culo en movimiento en el coraz\u00f3n del Mediterr\u00e1neo<\/h1>\n<p>En el acto de presentaci\u00f3n de la regata, celebrado el pasado 3 de julio en el Ayuntamiento, Marc Puig resalt\u00f3 la inestimable aportaci\u00f3n del mar a Barcelona y asegur\u00f3 que \u201cse trata de un espect\u00e1culo en movimiento hecho para la ciudad que se ha convertido en un referente para todo el mundo\u201d. Y es que no hay otra capital del mundo que albergue una regata de barcos cl\u00e1sicos como la que cada a\u00f1o acoge la capital catalana.<br \/>\nAdem\u00e1s, una de las particularidades de la Puig Vela Cl\u00e0ssica y uno de los motivos que la hacen \u00fanica, es que ocurre en el coraz\u00f3n de Barcelona: a 5 minutos de la Sagrada Familia, a 10 minutos del Barrio G\u00f3tico y a un paso de los mejores y m\u00e1s exclusivos restaurantes de la ciudad. Algo que ninguna otra capital del Mediterr\u00e1neo puede ofrecer a sus regatistas. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>A tres d\u00edas para su celebraci\u00f3n<\/p>\n","protected":false},"author":1,"featured_media":7624,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"class_list":["post-1670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La regata Puig Vela Cl\u00e0ssica convierte, un a\u00f1o m\u00e1s, a Barcelona en la capital n\u00e1utica del Mediterr\u00e1neo - Puig Vela Cl\u00e0ssica Barcelona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-convierte-un-ano-mas-a-barcelona-en-la-capital-nautica-del-mediterraneo-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La regata Puig Vela Cl\u00e0ssica convierte, un a\u00f1o m\u00e1s, a Barcelona en la capital n\u00e1utica del Mediterr\u00e1neo - Puig Vela Cl\u00e0ssica Barcelona\" \/>\n<meta property=\"og:description\" content=\"A tres d\u00edas para su celebraci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-convierte-un-ano-mas-a-barcelona-en-la-capital-nautica-del-mediterraneo-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Puig Vela Cl\u00e0ssica Barcelona\" \/>\n<meta property=\"article:published_time\" content=\"2012-07-09T13:13:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-21T22:00:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2012\/07\/ivedicion.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1490\" \/>\n\t<meta property=\"og:image:height\" content=\"743\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"velaclassica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"velaclassica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-convierte-un-ano-mas-a-barcelona-en-la-capital-nautica-del-mediterraneo-2\/\",\"url\":\"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-convierte-un-ano-mas-a-barcelona-en-la-capital-nautica-del-mediterraneo-2\/\",\"name\":\"La regata Puig Vela Cl\u00e0ssica convierte, un a\u00f1o m\u00e1s, a Barcelona en la capital n\u00e1utica del Mediterr\u00e1neo - Puig Vela Cl\u00e0ssica Barcelona\",\"isPartOf\":{\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-convierte-un-ano-mas-a-barcelona-en-la-capital-nautica-del-mediterraneo-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-convierte-un-ano-mas-a-barcelona-en-la-capital-nautica-del-mediterraneo-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2012\/07\/ivedicion.jpeg\",\"datePublished\":\"2012-07-09T13:13:45+00:00\",\"dateModified\":\"2024-01-21T22:00:16+00:00\",\"author\":{\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/0f1f6cd6f23050a19e91a3003de34c7e\"},\"breadcrumb\":{\"@id\":\"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-convierte-un-ano-mas-a-barcelona-en-la-capital-nautica-del-mediterraneo-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-convierte-un-ano-mas-a-barcelona-en-la-capital-nautica-del-mediterraneo-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-convierte-un-ano-mas-a-barcelona-en-la-capital-nautica-del-mediterraneo-2\/#primaryimage\",\"url\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2012\/07\/ivedicion.jpeg\",\"contentUrl\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2012\/07\/ivedicion.jpeg\",\"width\":1490,\"height\":743},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-convierte-un-ano-mas-a-barcelona-en-la-capital-nautica-del-mediterraneo-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mail.puigvelaclasica.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La regata Puig Vela Cl\u00e0ssica convierte, un a\u00f1o m\u00e1s, a Barcelona en la capital n\u00e1utica del Mediterr\u00e1neo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#website\",\"url\":\"https:\/\/www.puigvelaclassicabarcelona.com\/\",\"name\":\"Puig Vela Cl\u00e0ssica Barcelona\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.puigvelaclassicabarcelona.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/0f1f6cd6f23050a19e91a3003de34c7e\",\"name\":\"velaclassica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/18a97ff0e5d67038bad233b79246a7f922424d224871d207487c88e471e664c2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/18a97ff0e5d67038bad233b79246a7f922424d224871d207487c88e471e664c2?s=96&d=mm&r=g\",\"caption\":\"velaclassica\"},\"sameAs\":[\"https:\/\/puigvelaclassica.com\/\"],\"url\":\"https:\/\/puigvelaclassica.com\/es\/author\/velaclassica\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La regata Puig Vela Cl\u00e0ssica convierte, un a\u00f1o m\u00e1s, a Barcelona en la capital n\u00e1utica del Mediterr\u00e1neo - Puig Vela Cl\u00e0ssica Barcelona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-convierte-un-ano-mas-a-barcelona-en-la-capital-nautica-del-mediterraneo-2\/","og_locale":"es_ES","og_type":"article","og_title":"La regata Puig Vela Cl\u00e0ssica convierte, un a\u00f1o m\u00e1s, a Barcelona en la capital n\u00e1utica del Mediterr\u00e1neo - Puig Vela Cl\u00e0ssica Barcelona","og_description":"A tres d\u00edas para su celebraci\u00f3n","og_url":"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-convierte-un-ano-mas-a-barcelona-en-la-capital-nautica-del-mediterraneo-2\/","og_site_name":"Puig Vela Cl\u00e0ssica Barcelona","article_published_time":"2012-07-09T13:13:45+00:00","article_modified_time":"2024-01-21T22:00:16+00:00","og_image":[{"width":1490,"height":743,"url":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2012\/07\/ivedicion.jpeg","type":"image\/jpeg"}],"author":"velaclassica","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"velaclassica","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-convierte-un-ano-mas-a-barcelona-en-la-capital-nautica-del-mediterraneo-2\/","url":"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-convierte-un-ano-mas-a-barcelona-en-la-capital-nautica-del-mediterraneo-2\/","name":"La regata Puig Vela Cl\u00e0ssica convierte, un a\u00f1o m\u00e1s, a Barcelona en la capital n\u00e1utica del Mediterr\u00e1neo - Puig Vela Cl\u00e0ssica Barcelona","isPartOf":{"@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-convierte-un-ano-mas-a-barcelona-en-la-capital-nautica-del-mediterraneo-2\/#primaryimage"},"image":{"@id":"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-convierte-un-ano-mas-a-barcelona-en-la-capital-nautica-del-mediterraneo-2\/#primaryimage"},"thumbnailUrl":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2012\/07\/ivedicion.jpeg","datePublished":"2012-07-09T13:13:45+00:00","dateModified":"2024-01-21T22:00:16+00:00","author":{"@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/0f1f6cd6f23050a19e91a3003de34c7e"},"breadcrumb":{"@id":"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-convierte-un-ano-mas-a-barcelona-en-la-capital-nautica-del-mediterraneo-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-convierte-un-ano-mas-a-barcelona-en-la-capital-nautica-del-mediterraneo-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-convierte-un-ano-mas-a-barcelona-en-la-capital-nautica-del-mediterraneo-2\/#primaryimage","url":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2012\/07\/ivedicion.jpeg","contentUrl":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2012\/07\/ivedicion.jpeg","width":1490,"height":743},{"@type":"BreadcrumbList","@id":"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-convierte-un-ano-mas-a-barcelona-en-la-capital-nautica-del-mediterraneo-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mail.puigvelaclasica.com\/es\/"},{"@type":"ListItem","position":2,"name":"La regata Puig Vela Cl\u00e0ssica convierte, un a\u00f1o m\u00e1s, a Barcelona en la capital n\u00e1utica del Mediterr\u00e1neo"}]},{"@type":"WebSite","@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#website","url":"https:\/\/www.puigvelaclassicabarcelona.com\/","name":"Puig Vela Cl\u00e0ssica Barcelona","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.puigvelaclassicabarcelona.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/0f1f6cd6f23050a19e91a3003de34c7e","name":"velaclassica","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/18a97ff0e5d67038bad233b79246a7f922424d224871d207487c88e471e664c2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/18a97ff0e5d67038bad233b79246a7f922424d224871d207487c88e471e664c2?s=96&d=mm&r=g","caption":"velaclassica"},"sameAs":["https:\/\/puigvelaclassica.com\/"],"url":"https:\/\/puigvelaclassica.com\/es\/author\/velaclassica\/"}]}},"_links":{"self":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/posts\/1670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/comments?post=1670"}],"version-history":[{"count":1,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/posts\/1670\/revisions"}],"predecessor-version":[{"id":7629,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/posts\/1670\/revisions\/7629"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/media\/7624"}],"wp:attachment":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/media?parent=1670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/categories?post=1670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}