{"id":2951,"date":"2014-07-18T17:41:11","date_gmt":"2014-07-18T17:41:11","guid":{"rendered":"http:\/\/www.puigvelaclassica.com\/?p=2951"},"modified":"2024-01-21T20:47:26","modified_gmt":"2024-01-21T20:47:26","slug":"sin-viento-no-hay-regatas-las-de-hoy-suspendidas","status":"publish","type":"post","link":"https:\/\/puigvelaclassica.com\/es\/sin-viento-no-hay-regatas-las-de-hoy-suspendidas\/","title":{"rendered":"Sin viento no hay regatas: las de hoy, suspendidas"},"content":{"rendered":"<ul>\n<li>Se mantiene la clasificaci\u00f3n general del d\u00eda de ayer y ma\u00f1ana s\u00e1bado se torna como la jornada decisiva<\/li>\n<li>A falta de disputar las pruebas de ma\u00f1ana, el 12 metros Nyala se proclama virtual campe\u00f3n del Mundial Puig 12mR World Championship<\/li>\n<li>El Moonbeam IV celebra su centenario el mismo a\u00f1o del 100 Aniversario de Puig<\/li>\n<\/ul>\n<p><img decoding=\"async\" src=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2014\/07\/elpeter.jpeg\" alt=\"elpeter\" class=\"alignnone size-medium wp-image-3729\" \/><\/p>\n<p><strong>Barcelona, 18 de julio de 2014<\/strong>. La coincidencia en el d\u00eda de hoy del Campeonato Mundial Puig 12mR World Championship y la VII Puig Vela Cl\u00e0ssica Barcelona se ha traducido en un hervidero de regatistas en los pantalanes desde primera hora de la ma\u00f1ana. M\u00e1s de 600 tripulantes pon\u00edan a punto estas verdaderas joyas n\u00e1uticas para, sobre las 11:30, dirigirse al campo de regatas formando toda una hilera de m\u00e1s de medio centenar de embarcaciones por el Moll de la Fusta, una espectacular imagen que ha podido el p\u00fablico asistente en el Pot Vell.<\/p>\n<p>Tras la salida al mar, la falta de viento ha vuelto a ser la gran protagonista de la jornada. Despu\u00e9s de casi tres horas a la espera de que la climatolog\u00eda acompa\u00f1ara, finalmente las dos pruebas han sido anuladas, por lo que las embarcaciones han vuelto al Real Club N\u00e1utico de Barcelona conservando la clasificaci\u00f3n de las jornadas anteriores.<\/p>\n<h1>A expensas del viento<\/h1>\n<p>Tras cuatro jornadas sin faltar a la cita, el viento hoy se ha tomado el d\u00eda libre. La particular situaci\u00f3n meteorol\u00f3gica de Barcelona, con la transici\u00f3n de temperaturas que hoy ha comenzado, ha impedido que el esperado viento del sur hiciera acto de presencia. Un Sureste parec\u00eda que iba a tomar el relevo al espl\u00e9ndido Garb\u00ed que ayer obsequio a la flota de la Puig Vela Cl\u00e0ssica Barcelona, pero finalmente el cielo se ha ido tapando hasta acabar con la suave brisa que permiti\u00f3 tomar la salida en ambos campos de regatas.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-2952\" alt=\"El atardecer en el pantalan del Real Club Nautico de Barcelona\" src=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2014\/07\/El-atardecer-en-el-pantalan-del-Real-Club-Nautico-de-Barcelona.jpeg\" width=\"266\" height=\"400\" \/><\/p>\n<p>Primero fueron los 12 Metros quienes a punto de finalizar el primer tramo ve\u00edan como el comit\u00e9 de regatas deb\u00eda parar la prueba en marcha. Tras un aplazamiento esperando la evoluci\u00f3n del viento, que no aument\u00f3 de intensidad, mando de regreso a la flota a casa.<\/p>\n<p>As\u00ed las cosas, y a falta de dos posibles pruebas por disputar ma\u00f1ana, el Nyala es virtual Campe\u00f3n del Mundo. Su impecable casillero parcial le reserva un as en la manga, ya que su actual descarte es un segundo puesto, y si le sum\u00e1semos en alguna de las dos posibles nuevas mangas un sexto puesto correspondiente al \u00faltimo clasificado, totalizar\u00eda 14 puntos, frente a los 15 que sumar\u00eda el Trivia en caso de a\u00f1adir dos primeros a sus actuales 13 puntos.<\/p>\n<p>Pero no faltar\u00e1 emoci\u00f3n en la recta final del Campeonato del Mundo de 12 metros, ya que las dos plazas restantes del podio se van a competir intensamente. Los Trivia, Vanity V y Wings se clasifican por este orden con 13, 14 y 15 puntos respectivamente<\/p>\n<p>La prueba de cl\u00e1sicos ha tenido el mismo final que la de 12 metros. Tras un \u00faltimo intento de comenzar la regata, finalmente se ha acabado suspendiendo. As\u00ed, el marcador de las cuatro flotas se mantiene inalterable tras la primera prueba disputada ayer. El Moonbeam IV en Big Boats, El Samurai en Cl\u00e1sicos, el Peter en \u00c9poca Marconi y el Marigold en \u00c9poca Cangreja, partir\u00e1n ma\u00f1ana hacia el campo de regatas a defender el liderato de sus categor\u00edas.<\/p>\n<p>El Moonbeam IV celebra sus 100 a\u00f1os liderando la clasificaci\u00f3n de la VII Puig Vela Cl\u00e0ssica<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"size-medium wp-image-2953 aligncenter\" alt=\"El centenario Moonbeam IV surcando las aguas barcelonesas_B\" src=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2014\/07\/El-centenario-Moonbeam-IV-surcando-las-aguas-barcelonesas_B.jpeg\"  \/><\/p>\n<p>Este impresionante velero, dise\u00f1ado por el renombrado William Fife III, es uno de los pocos cutter \u00e1uricos cl\u00e1sicos que siguen navegando a d\u00eda de hoy. Se trata de uno de los barcos m\u00e1s bellos del mundo, no s\u00f3lo por su exterior, sino tambi\u00e9n por sus lujosos detalles. Se empez\u00f3 a construir en 1914, pero la Primera Guerra Mundial provoc\u00f3 que no fuese botado hasta 1929. El Moonbeam IV cuenta con la peculiaridad de haber sido el barco elegido por Rainiero de M\u00f3naco y Grace Kelly para pasar su luna de miel en 1956.<\/p>\n<p>Este 2014 ha dado la coincidencia de que tanto la embarcaci\u00f3n como Puig, organizador de la regata, cumplen 100 a\u00f1os. Por ello, esta tarde se ha celebrado el centenario en el Real Club N\u00e1utico de Barcelona y Marc Puig, presidente de Puig, ha sido el encargado de homenajear al m\u00edtico velero con una tarta con el n\u00famero ocho, d\u00edgito de la vela de este barco cargado de historia.<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"size-medium wp-image-2955 aligncenter\" alt=\"Marc Puig, Enrique Corominas, Dami\u00e1n Ribas y la tripulacion del Moonbeam IV celebran el 100 aniversario del velero\" src=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2014\/07\/Marc-Puig-Enrique-Corominas-Damia\u0301n-Ribas-y-la-tripulacion-del-Moonbeam-IV-celebran-el-100-aniversario-del-velero-1.jpeg\"\/><\/p>\n<h1>El barniz y el bronce de los cl\u00e1sicos tambi\u00e9n atrae a las figuras<\/h1>\n<p>Entre las maderas nobles y los bronces de estas joyas n\u00e1uticas se esconden regatistas de \u00e9lite que han cosechado numerosos \u00e9xitos en el \u00faltimo cuarto de siglo. En esta VII edici\u00f3n de la Puig Vela Cl\u00e0ssica compiten muchas figuras de la vela moderna, desde regatistas ol\u00edmpicos, navegantes oce\u00e1nicos hasta estrellas de la America\u2019s Cup.<\/p>\n<p>La presencia de Francesco Bruni, t\u00e1ctico del Prada en la \u00faltima America\u2019s Cup y conocido en nuestras aguas por sus campa\u00f1as en el TP52 Matador, parece un gui\u00f1o a la historia. Bruni est\u00e1 al mando del Nyala, m\u00e1ximo aspirante al t\u00edtulo mundial de 12 Metros, los barcos que escribieron la primera p\u00e1gina de oro de la regata m\u00e1s importante.<\/p>\n<p>Tambi\u00e9n vinculado a la prestigiosa competici\u00f3n navega estos d\u00edas en Barcelona Guido Cavallazzi, uno de los gur\u00fas mundiales del dise\u00f1o de velas que trabaj\u00f3 en equipos como Il Moro di Venecia, Young Am\u00e9rica y m\u00e1s recientemente en el Prada. Cavalazzi compite en Barcelona en el 12 Metros Emilia.<\/p>\n<p>Hay muchos m\u00e1s, pero Mauro Perlaschier merece un lugar en cualquier Hall of Fame de una regata que se precie. Perlaschier ya es un habitual de la Puig Vela Cl\u00e0ssica Barcelona a bordo del Peter.<\/p>\n<p>Por parte espa\u00f1ola, la vela oce\u00e1nica est\u00e1 representada por Alex Pella y Cali Sanmart\u00ed. Pella est\u00e1 llamado a escribir las pr\u00f3ximas p\u00e1ginas de la vela oce\u00e1nica en solitario, tras sus campa\u00f1as de Mini Transat, la pasada Barcelona World Race, la Route des Princes y diversas regatas transatl\u00e1nticas. Esta vez compite bajo las \u00f3rdenes de su hermano Borja en el Galvana. Cali Sanmart\u00ed lo hace en el Alba de Dami\u00e1n Ribas, donde sin duda puede aplicar su experiencia de la pasada Barcelona World Race.<\/p>\n<p>La regatista ol\u00edmpica Laia Tutz\u00f3 comparte maniobras en el Alba con Sanmart\u00ed, como antes lo hizo con Natalia V\u00eda Dufresne en el 470 que les llev\u00f3 a competir juntas en los Juegos de Pekin 2008. V\u00eda Dufresne ya se colg\u00f3 la plata ol\u00edmpica con s\u00f3lo 19 a\u00f1os, compitiendo en los Juegos de Barcelona 92 en la clase Europa. Repiti\u00f3 color de medalla 12 a\u00f1os m\u00e1s tarde, cuando gano la plata en Atenas 2004, esta vez en la categor\u00eda 470, en la que acumula m\u00faltiples honores en mundiales y continentales.<\/p>\n<p>Y todav\u00eda m\u00e1s significativo el caso de Luis Mart\u00ednez Doreste. Miembro de la m\u00edtica saga canaria, su carrera ol\u00edmpica le permiti\u00f3 representar a Espa\u00f1a en los Juegos de Sydney 2000 y Atenas 2004, ambas en la clase Laser. Pero una de las grandes pasiones de Luis le est\u00e1 haciendo todav\u00eda m\u00e1s popular en la familia de la vela, cuando coge el micro y levanta el \u00e1nimo del p\u00fablico que asiste a los conciertos del grupo musical The Tall Tutsies, que cerrar\u00e1n por cuarta vez consecutiva la fiesta que cierra la Puig Vela Cl\u00e0ssica Barcelona.<\/p>\n<p><a title=\"Clasificaciones\" href=\"http:\/\/www.puigvelaclassica.com\/es\/regata-2\/puig-vela-classica\/clasificaciones\/\" target=\"_blank\" rel=\"noopener\">Clasificaciones generales VII Puig Vela Cl\u00e0ssica Barcelona<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>VII Puig Vela Cl\u00e0ssica Barcelona  y Mundial 12m<\/p>\n","protected":false},"author":1,"featured_media":7456,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"class_list":["post-2951","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sin viento no hay regatas: las de hoy, suspendidas - Puig Vela Cl\u00e0ssica Barcelona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/puigvelaclassica.com\/es\/sin-viento-no-hay-regatas-las-de-hoy-suspendidas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sin viento no hay regatas: las de hoy, suspendidas - Puig Vela Cl\u00e0ssica Barcelona\" \/>\n<meta property=\"og:description\" content=\"VII Puig Vela Cl\u00e0ssica Barcelona y Mundial 12m\" \/>\n<meta property=\"og:url\" content=\"https:\/\/puigvelaclassica.com\/es\/sin-viento-no-hay-regatas-las-de-hoy-suspendidas\/\" \/>\n<meta property=\"og:site_name\" content=\"Puig Vela Cl\u00e0ssica Barcelona\" \/>\n<meta property=\"article:published_time\" content=\"2014-07-18T17:41:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-21T20:47:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2014\/07\/elpeter.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1912\" \/>\n\t<meta property=\"og:image:height\" content=\"1226\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"velaclassica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"velaclassica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/puigvelaclassica.com\/es\/sin-viento-no-hay-regatas-las-de-hoy-suspendidas\/\",\"url\":\"https:\/\/puigvelaclassica.com\/es\/sin-viento-no-hay-regatas-las-de-hoy-suspendidas\/\",\"name\":\"Sin viento no hay regatas: las de hoy, suspendidas - Puig Vela Cl\u00e0ssica Barcelona\",\"isPartOf\":{\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/puigvelaclassica.com\/es\/sin-viento-no-hay-regatas-las-de-hoy-suspendidas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/puigvelaclassica.com\/es\/sin-viento-no-hay-regatas-las-de-hoy-suspendidas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2014\/07\/elpeter.jpeg\",\"datePublished\":\"2014-07-18T17:41:11+00:00\",\"dateModified\":\"2024-01-21T20:47:26+00:00\",\"author\":{\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/0f1f6cd6f23050a19e91a3003de34c7e\"},\"breadcrumb\":{\"@id\":\"https:\/\/puigvelaclassica.com\/es\/sin-viento-no-hay-regatas-las-de-hoy-suspendidas\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/puigvelaclassica.com\/es\/sin-viento-no-hay-regatas-las-de-hoy-suspendidas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/puigvelaclassica.com\/es\/sin-viento-no-hay-regatas-las-de-hoy-suspendidas\/#primaryimage\",\"url\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2014\/07\/elpeter.jpeg\",\"contentUrl\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2014\/07\/elpeter.jpeg\",\"width\":1912,\"height\":1226},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/puigvelaclassica.com\/es\/sin-viento-no-hay-regatas-las-de-hoy-suspendidas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mail.puigvelaclasica.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sin viento no hay regatas: las de hoy, suspendidas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#website\",\"url\":\"https:\/\/www.puigvelaclassicabarcelona.com\/\",\"name\":\"Puig Vela Cl\u00e0ssica Barcelona\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.puigvelaclassicabarcelona.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/0f1f6cd6f23050a19e91a3003de34c7e\",\"name\":\"velaclassica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/18a97ff0e5d67038bad233b79246a7f922424d224871d207487c88e471e664c2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/18a97ff0e5d67038bad233b79246a7f922424d224871d207487c88e471e664c2?s=96&d=mm&r=g\",\"caption\":\"velaclassica\"},\"sameAs\":[\"https:\/\/puigvelaclassica.com\/\"],\"url\":\"https:\/\/puigvelaclassica.com\/es\/author\/velaclassica\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sin viento no hay regatas: las de hoy, suspendidas - Puig Vela Cl\u00e0ssica Barcelona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/puigvelaclassica.com\/es\/sin-viento-no-hay-regatas-las-de-hoy-suspendidas\/","og_locale":"es_ES","og_type":"article","og_title":"Sin viento no hay regatas: las de hoy, suspendidas - Puig Vela Cl\u00e0ssica Barcelona","og_description":"VII Puig Vela Cl\u00e0ssica Barcelona y Mundial 12m","og_url":"https:\/\/puigvelaclassica.com\/es\/sin-viento-no-hay-regatas-las-de-hoy-suspendidas\/","og_site_name":"Puig Vela Cl\u00e0ssica Barcelona","article_published_time":"2014-07-18T17:41:11+00:00","article_modified_time":"2024-01-21T20:47:26+00:00","og_image":[{"width":1912,"height":1226,"url":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2014\/07\/elpeter.jpeg","type":"image\/jpeg"}],"author":"velaclassica","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"velaclassica","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/puigvelaclassica.com\/es\/sin-viento-no-hay-regatas-las-de-hoy-suspendidas\/","url":"https:\/\/puigvelaclassica.com\/es\/sin-viento-no-hay-regatas-las-de-hoy-suspendidas\/","name":"Sin viento no hay regatas: las de hoy, suspendidas - Puig Vela Cl\u00e0ssica Barcelona","isPartOf":{"@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/puigvelaclassica.com\/es\/sin-viento-no-hay-regatas-las-de-hoy-suspendidas\/#primaryimage"},"image":{"@id":"https:\/\/puigvelaclassica.com\/es\/sin-viento-no-hay-regatas-las-de-hoy-suspendidas\/#primaryimage"},"thumbnailUrl":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2014\/07\/elpeter.jpeg","datePublished":"2014-07-18T17:41:11+00:00","dateModified":"2024-01-21T20:47:26+00:00","author":{"@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/0f1f6cd6f23050a19e91a3003de34c7e"},"breadcrumb":{"@id":"https:\/\/puigvelaclassica.com\/es\/sin-viento-no-hay-regatas-las-de-hoy-suspendidas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/puigvelaclassica.com\/es\/sin-viento-no-hay-regatas-las-de-hoy-suspendidas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/puigvelaclassica.com\/es\/sin-viento-no-hay-regatas-las-de-hoy-suspendidas\/#primaryimage","url":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2014\/07\/elpeter.jpeg","contentUrl":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2014\/07\/elpeter.jpeg","width":1912,"height":1226},{"@type":"BreadcrumbList","@id":"https:\/\/puigvelaclassica.com\/es\/sin-viento-no-hay-regatas-las-de-hoy-suspendidas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mail.puigvelaclasica.com\/es\/"},{"@type":"ListItem","position":2,"name":"Sin viento no hay regatas: las de hoy, suspendidas"}]},{"@type":"WebSite","@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#website","url":"https:\/\/www.puigvelaclassicabarcelona.com\/","name":"Puig Vela Cl\u00e0ssica Barcelona","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.puigvelaclassicabarcelona.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/0f1f6cd6f23050a19e91a3003de34c7e","name":"velaclassica","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/18a97ff0e5d67038bad233b79246a7f922424d224871d207487c88e471e664c2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/18a97ff0e5d67038bad233b79246a7f922424d224871d207487c88e471e664c2?s=96&d=mm&r=g","caption":"velaclassica"},"sameAs":["https:\/\/puigvelaclassica.com\/"],"url":"https:\/\/puigvelaclassica.com\/es\/author\/velaclassica\/"}]}},"_links":{"self":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/posts\/2951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/comments?post=2951"}],"version-history":[{"count":2,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/posts\/2951\/revisions"}],"predecessor-version":[{"id":7467,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/posts\/2951\/revisions\/7467"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/media\/7456"}],"wp:attachment":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/media?parent=2951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/categories?post=2951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}