{"id":4743,"date":"2017-07-12T12:51:57","date_gmt":"2017-07-12T12:51:57","guid":{"rendered":"http:\/\/www.puigvelaclassica.com\/?p=4743"},"modified":"2024-01-21T11:09:28","modified_gmt":"2024-01-21T11:09:28","slug":"la-puig-vela-classica-barcelona-inicia-su-decima-edicion","status":"publish","type":"post","link":"https:\/\/puigvelaclassica.com\/es\/la-puig-vela-classica-barcelona-inicia-su-decima-edicion\/","title":{"rendered":"La Puig Vela Cl\u00e0ssica Barcelona inicia su d\u00e9cima edici\u00f3n"},"content":{"rendered":"<ul>\n<li>56 barcos, r\u00e9cord de inscritos, 12 pa\u00edses representados y m\u00e1s de 900 navegantes<\/li>\n<li>La regata de referencia cumple 10 a\u00f1os acercando a Barcelona la \u00e9lite de la historia de la vela deportiva<\/li>\n<li>Este \u201cmuseo vivo y flotante\u201d se podr\u00e1 disfrutar tanto en el mar como desde la costa y playas de Barcelona<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2017\/07\/Cartel-X-edicio\u0301n-Puig-Vela-Cla\u0300ssica-Barcelona-1.jpeg\" alt=\"Cartel X edici\u00f3n Puig Vela Cl\u00e0ssica Barcelona (1)\" width=\"1024\" height=\"721\" class=\"alignnone size-full wp-image-4744\" \/><\/p>\n<p>Esta tarde da comienzo la X regata Puig Vela Cl\u00e0ssica Barcelona, una edici\u00f3n marcada por el record hist\u00f3rico de barcos participantes -56 veleros inscritos- as\u00ed como por los pa\u00edses representados -12 banderas de Europa y Am\u00e9rica-. Estas estupendas cifras convertir\u00e1n a Barcelona hasta el 15 de julio en el epicentro mundial de la vela cl\u00e1sica y de \u00e9poca.<\/p>\n<p>Cerca de un millar de regatistas procedentes de Espa\u00f1a y pa\u00edses como Francia, Reino Unido, Italia, Malta, Uruguay o Argentina, competir\u00e1n en las aguas de la capital catalana ofreciendo un espect\u00e1culo \u00fanico de la n\u00e1utica m\u00e1s pura.<\/p>\n<p><strong>Una edici\u00f3n de aniversario con ejemplares \u00fanicos que han marcado la historia de la vela deportiva<\/strong><\/p>\n<p>Por primera vez la PUIG Vela Cl\u00e0ssica re\u00fane a los ganadores de la edici\u00f3n anterior, el Moonbeam III en Big Boats, Sonata en \u00c9poca Marconi, Marigold en \u00c9poca Cangreja, Guia en Cl\u00e1sicos A y Alba en Cl\u00e1sicos B.<\/p>\n<p>Tambi\u00e9n se producen algunos estrenos relevantes en la esta hist\u00f3rica prueba, destacando la presencia del impresionante Big Boat Xarifa 1927, de m\u00e1s de 50 metros de eslora, el Cl\u00e1sico Il Moro di Venezia I, que inici\u00f3 una leyenda en los primeros a\u00f1os setenta y, de \u00c9poca, el argentino Cippino, llegado expresamente desde su pa\u00eds para competir por primera vez en aguas europeas.<br \/>\nTodos ellos competir\u00e1n en las categor\u00edas de \u00c9poca Marconi y Cangreja (barcos realizados en madera o metal botados antes del 31 de diciembre de 1949); Cl\u00e1sicos A y B (construidos en madera o metal conforme a los planos originales y botados entre el 1 de enero de 1950 y el 31 de diciembre de 1975) y Big Boat (barcos de \u00c9poca y Cl\u00e1sicos con eslora a partir de 25 metros).<\/p>\n<p><strong>Algunos de m\u00e1s de un siglo, otros \u201csolo\u201d cumplen 90 a\u00f1os<\/strong><\/p>\n<p>Esta d\u00e9cima edici\u00f3n supone un importante hito para el Gypsy de \u201cPetete\u201d Rubio, que celebra el 90 aniversario del barco. \u201cQueremos aprovechar esta regata para festejar el aniversario del Gypsy. Hemos participado en todas las ediciones de la Puig Vela Cl\u00e0ssica y nos gustar\u00eda ganar este a\u00f1o. Tuvimos el honor de inaugurar el palmar\u00e9s del trofeo \u00c9poca Cangreja y ser\u00eda la guinda del pastel poderlo hacer de nuevo\u201d. Como detalle de la efem\u00e9ride, la organizaci\u00f3n ha concedido el dorsal 90 al Gypsy para sumarse a la celebraci\u00f3n.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2017\/07\/Imagen-Moonbeam-IV-1.jpeg\" alt=\"Imagen Moonbeam IV (1)\" width=\"1024\" height=\"683\" class=\"alignnone size-full wp-image-4745\" \/><\/p>\n<p><strong>Barcelona, epicentro de la n\u00e1utica m\u00e1s cl\u00e1sica<\/strong><\/p>\n<p>Cada vez son m\u00e1s quienes se acercan a la capital catalana para asistir a este espect\u00e1culo, famoso por la belleza de su escenario y la riqueza hist\u00f3rica y cultural de su entorno. Puig convierte un a\u00f1o m\u00e1s, las aguas de la capital catalana en un espect\u00e1culo n\u00e1utico que se ha convertido en un referente social y deportivo veraniego en la costa barcelonesa por su extraordinaria belleza y elegancia.<\/p>\n<p>Este evento podr\u00e1 contemplarse desde diferentes emplazamientos como el Puerto Viejo o el Puerto Ol\u00edmpico, as\u00ed como desde las mismas playas de la Barceloneta o de Sant Miquel. Por otro lado, quienes dispongan de un barco propio o decidan alquilarlo, tendr\u00e1n el lujo de disfrutar de la cercan\u00eda de estas embarcaciones de leyenda en el mar.<\/p>\n<p>Y es que no hay otra capital del mundo que albergue una regata de barcos cl\u00e1sicos como la que acoge cada a\u00f1o Barcelona. Entre los destinos de ensue\u00f1o donde se celebran los eventos de veleros cl\u00e1sicos como Cannes, Antibes, Antigua, Newport o la Isla de Wight, tan s\u00f3lo uno de ellos es una capital de importancia y trascendencia internacional: Barcelona.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>56 barcos, r\u00e9cord de inscritos, 12 pa\u00edses representados y m\u00e1s de 900 navegantes La regata de referencia cumple 10 a\u00f1os acercando a Barcelona la \u00e9lite de la historia de la vela deportiva Este \u201cmuseo vivo y flotante\u201d se podr\u00e1 disfrutar tanto en el mar como desde la costa y playas de Barcelona Esta tarde da [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7203,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"class_list":["post-4743","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Puig Vela Cl\u00e0ssica Barcelona inicia su d\u00e9cima edici\u00f3n - Puig Vela Cl\u00e0ssica Barcelona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/puigvelaclassica.com\/es\/la-puig-vela-classica-barcelona-inicia-su-decima-edicion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Puig Vela Cl\u00e0ssica Barcelona inicia su d\u00e9cima edici\u00f3n\" \/>\n<meta property=\"og:description\" content=\"56 barcos, record de inscritos, 12 pa\u00edses representados y m\u00e1s de 900 navegantes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/puigvelaclassica.com\/es\/la-puig-vela-classica-barcelona-inicia-su-decima-edicion\/\" \/>\n<meta property=\"og:site_name\" content=\"Puig Vela Cl\u00e0ssica Barcelona\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-12T12:51:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-21T11:09:28+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.puigvelaclassica.com\/wp-content\/uploads\/2017\/07\/Imagen-Moonbeam-IV-1.jpg\" \/>\n<meta name=\"author\" content=\"velaclassica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"La Puig Vela Cl\u00e0ssica Barcelona inicia su d\u00e9cima edici\u00f3n\" \/>\n<meta name=\"twitter:description\" content=\"56 barcos, record de inscritos, 12 pa\u00edses representados y m\u00e1s de 900 navegantes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"velaclassica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/puigvelaclassica.com\/es\/la-puig-vela-classica-barcelona-inicia-su-decima-edicion\/\",\"url\":\"https:\/\/puigvelaclassica.com\/es\/la-puig-vela-classica-barcelona-inicia-su-decima-edicion\/\",\"name\":\"La Puig Vela Cl\u00e0ssica Barcelona inicia su d\u00e9cima edici\u00f3n - Puig Vela Cl\u00e0ssica Barcelona\",\"isPartOf\":{\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/puigvelaclassica.com\/es\/la-puig-vela-classica-barcelona-inicia-su-decima-edicion\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/puigvelaclassica.com\/es\/la-puig-vela-classica-barcelona-inicia-su-decima-edicion\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2017\/07\/Imagen-Moonbeam-IV-1.jpeg\",\"datePublished\":\"2017-07-12T12:51:57+00:00\",\"dateModified\":\"2024-01-21T11:09:28+00:00\",\"author\":{\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/0f1f6cd6f23050a19e91a3003de34c7e\"},\"breadcrumb\":{\"@id\":\"https:\/\/puigvelaclassica.com\/es\/la-puig-vela-classica-barcelona-inicia-su-decima-edicion\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/puigvelaclassica.com\/es\/la-puig-vela-classica-barcelona-inicia-su-decima-edicion\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/puigvelaclassica.com\/es\/la-puig-vela-classica-barcelona-inicia-su-decima-edicion\/#primaryimage\",\"url\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2017\/07\/Imagen-Moonbeam-IV-1.jpeg\",\"contentUrl\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2017\/07\/Imagen-Moonbeam-IV-1.jpeg\",\"width\":1024,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/puigvelaclassica.com\/es\/la-puig-vela-classica-barcelona-inicia-su-decima-edicion\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mail.puigvelaclasica.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Puig Vela Cl\u00e0ssica Barcelona inicia su d\u00e9cima edici\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#website\",\"url\":\"https:\/\/www.puigvelaclassicabarcelona.com\/\",\"name\":\"Puig Vela Cl\u00e0ssica Barcelona\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.puigvelaclassicabarcelona.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/0f1f6cd6f23050a19e91a3003de34c7e\",\"name\":\"velaclassica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/18a97ff0e5d67038bad233b79246a7f922424d224871d207487c88e471e664c2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/18a97ff0e5d67038bad233b79246a7f922424d224871d207487c88e471e664c2?s=96&d=mm&r=g\",\"caption\":\"velaclassica\"},\"sameAs\":[\"https:\/\/puigvelaclassica.com\/\"],\"url\":\"https:\/\/puigvelaclassica.com\/es\/author\/velaclassica\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Puig Vela Cl\u00e0ssica Barcelona inicia su d\u00e9cima edici\u00f3n - Puig Vela Cl\u00e0ssica Barcelona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/puigvelaclassica.com\/es\/la-puig-vela-classica-barcelona-inicia-su-decima-edicion\/","og_locale":"es_ES","og_type":"article","og_title":"La Puig Vela Cl\u00e0ssica Barcelona inicia su d\u00e9cima edici\u00f3n","og_description":"56 barcos, record de inscritos, 12 pa\u00edses representados y m\u00e1s de 900 navegantes","og_url":"https:\/\/puigvelaclassica.com\/es\/la-puig-vela-classica-barcelona-inicia-su-decima-edicion\/","og_site_name":"Puig Vela Cl\u00e0ssica Barcelona","article_published_time":"2017-07-12T12:51:57+00:00","article_modified_time":"2024-01-21T11:09:28+00:00","og_image":[{"url":"http:\/\/www.puigvelaclassica.com\/wp-content\/uploads\/2017\/07\/Imagen-Moonbeam-IV-1.jpg","type":"","width":"","height":""}],"author":"velaclassica","twitter_card":"summary_large_image","twitter_title":"La Puig Vela Cl\u00e0ssica Barcelona inicia su d\u00e9cima edici\u00f3n","twitter_description":"56 barcos, record de inscritos, 12 pa\u00edses representados y m\u00e1s de 900 navegantes","twitter_misc":{"Escrito por":"velaclassica","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/puigvelaclassica.com\/es\/la-puig-vela-classica-barcelona-inicia-su-decima-edicion\/","url":"https:\/\/puigvelaclassica.com\/es\/la-puig-vela-classica-barcelona-inicia-su-decima-edicion\/","name":"La Puig Vela Cl\u00e0ssica Barcelona inicia su d\u00e9cima edici\u00f3n - Puig Vela Cl\u00e0ssica Barcelona","isPartOf":{"@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/puigvelaclassica.com\/es\/la-puig-vela-classica-barcelona-inicia-su-decima-edicion\/#primaryimage"},"image":{"@id":"https:\/\/puigvelaclassica.com\/es\/la-puig-vela-classica-barcelona-inicia-su-decima-edicion\/#primaryimage"},"thumbnailUrl":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2017\/07\/Imagen-Moonbeam-IV-1.jpeg","datePublished":"2017-07-12T12:51:57+00:00","dateModified":"2024-01-21T11:09:28+00:00","author":{"@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/0f1f6cd6f23050a19e91a3003de34c7e"},"breadcrumb":{"@id":"https:\/\/puigvelaclassica.com\/es\/la-puig-vela-classica-barcelona-inicia-su-decima-edicion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/puigvelaclassica.com\/es\/la-puig-vela-classica-barcelona-inicia-su-decima-edicion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/puigvelaclassica.com\/es\/la-puig-vela-classica-barcelona-inicia-su-decima-edicion\/#primaryimage","url":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2017\/07\/Imagen-Moonbeam-IV-1.jpeg","contentUrl":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2017\/07\/Imagen-Moonbeam-IV-1.jpeg","width":1024,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/puigvelaclassica.com\/es\/la-puig-vela-classica-barcelona-inicia-su-decima-edicion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mail.puigvelaclasica.com\/es\/"},{"@type":"ListItem","position":2,"name":"La Puig Vela Cl\u00e0ssica Barcelona inicia su d\u00e9cima edici\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#website","url":"https:\/\/www.puigvelaclassicabarcelona.com\/","name":"Puig Vela Cl\u00e0ssica Barcelona","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.puigvelaclassicabarcelona.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/0f1f6cd6f23050a19e91a3003de34c7e","name":"velaclassica","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/18a97ff0e5d67038bad233b79246a7f922424d224871d207487c88e471e664c2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/18a97ff0e5d67038bad233b79246a7f922424d224871d207487c88e471e664c2?s=96&d=mm&r=g","caption":"velaclassica"},"sameAs":["https:\/\/puigvelaclassica.com\/"],"url":"https:\/\/puigvelaclassica.com\/es\/author\/velaclassica\/"}]}},"_links":{"self":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/posts\/4743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/comments?post=4743"}],"version-history":[{"count":1,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/posts\/4743\/revisions"}],"predecessor-version":[{"id":7208,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/posts\/4743\/revisions\/7208"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/media\/7203"}],"wp:attachment":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/media?parent=4743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/categories?post=4743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}