{"id":4869,"date":"2017-07-21T09:33:45","date_gmt":"2017-07-21T09:33:45","guid":{"rendered":"http:\/\/www.puigvelaclassica.com\/?p=4869"},"modified":"2024-01-21T10:56:10","modified_gmt":"2024-01-21T10:56:10","slug":"la-regata-puig-vela-classica-barcelona-se-consolida-en-su-decimo-aniversario-como-uno-de-los-circuitos-de-vela-clasica-mas-importantes-del-mediterraneo","status":"publish","type":"post","link":"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-barcelona-se-consolida-en-su-decimo-aniversario-como-uno-de-los-circuitos-de-vela-clasica-mas-importantes-del-mediterraneo\/","title":{"rendered":"La regata Puig Vela Cl\u00e0ssica Barcelona se consolida en su d\u00e9cimo aniversario como uno de los circuitos de vela cl\u00e1sica m\u00e1s importantes del Mediterr\u00e1neo"},"content":{"rendered":"<ul>\n<ul>\n<li><strong>Cippino, Guia, Alba, Kelpie of Falmouth y Moonbeam III se proclamaron vencedores en una de las finales m\u00e1s re\u00f1idas de la historia de la regata, que comenz\u00f3 con empates en cuatro de las cinco categor\u00edas<\/strong><\/li>\n<li><strong>M\u00e1s de 50 barcos de 12 pa\u00edses y 600 navegantes han competido en la edici\u00f3n del 10 aniversario de la regata de cl\u00e1sicos con el litoral barcelon\u00e9s como tel\u00f3n de fondo<\/strong><\/li>\n<li><strong>Historias tan interesantes como el 90 aniversario del Gipsy o la presencia por primera vez de embarcaciones tan destacadas como las italianas Il Moro di Venezia I o el Corsario II, de la Armada Italiana, han puesto, un a\u00f1o m\u00e1s, la nota m\u00e1s social a esta prueba deportiva<\/strong><\/li>\n<\/ul>\n<\/ul>\n<p>Este a\u00f1o ha tenido lugar la d\u00e9cima edici\u00f3n de la regata Puig Vela Cl\u00e0ssica Barcelona, una competici\u00f3n que ha celebrado sus diez a\u00f1os de vida con r\u00e9cord hist\u00f3rico de embarcaciones y una emocionante lucha ofreciendo un espect\u00e1culo competitivo de primera categor\u00eda y con un desenlace re\u00f1ido hasta el \u00faltimo minuto.<br \/>\nEntre el 12 y el 15 de julio las aguas de Barcelona han sido testigo de un espect\u00e1culo de la n\u00e1utica m\u00e1s pura. Los m\u00e1s de 50 barcos participantes \u2013llegando a r\u00e9cord de inscritos- llegados de 12 pa\u00edses diferentes casi un millar de navegantes, han convertido a la ciudad, un a\u00f1o m\u00e1s, en la capital mundial de la vela cl\u00e1sica y de \u00e9poca.<br \/>\nCerca de un millar de regatistas procedentes de Espa\u00f1a y pa\u00edses como Francia, Reino Unido, Italia, Malta, Uruguay o Argentina, han competido en las aguas de la capital catalana ofreciendo un espect\u00e1culo n\u00e1utico en el mundo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4870\" src=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2017\/07\/Puig_170713_nm_1277.jpeg\" alt=\"X Regata Puig Vela Classica_2017\" width=\"2000\" height=\"728\" \/><\/p>\n<p><strong>Una edici\u00f3n de aniversario con embarcaciones \u00fanicas que han marcado la historia de la vela deportiva<\/strong><br \/>\nEste a\u00f1o la Puig Vela Cl\u00e0ssica se vest\u00eda con sus mejores galas para celebrar la d\u00e9cima edici\u00f3n. Por primera vez los cinco vencedores de la anterior edici\u00f3n (<strong>Moonbeam III, Alba, Guia, Sonata y Marigold<\/strong>) defendieron el t\u00edtulo con suerte dispar, y la flota vio el estreno de los italianos <strong>Il Moro di Venezia I y Corsario II<\/strong>; el impresionante Big Boat <strong>Xarifa 1927<\/strong>; el franc\u00e9s <strong>Saggitarius,<\/strong> as\u00ed como del argentino<strong> Cippino<\/strong> que adem\u00e1s se estrenaba en aguas europeas. Tambi\u00e9n cumpli\u00f3 d\u00e9cada el <strong>Gipsy<\/strong>, que celebraba sus 90 a\u00f1os y sigue sin perderse ninguna edici\u00f3n de la Puig Vela Cl\u00e0ssica Barcelona.<br \/>\nDurante las tres jornadas de competici\u00f3n el viento quiso sumarse a las celebraciones, soplando siempre por encima de los 10 nudos de intensidad y solo provoc\u00f3 el segundo d\u00eda un corto aplazamiento de la salida. Los regatas combinaron un recorrido costero de 17 millas el primer d\u00eda con sendos recorridos de boyas (entre 10 y 13 millas) en las siguientes dos jornadas, discurriendo todos ellos frente a las playas del litoral barcelon\u00e9s.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4847\" src=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2017\/07\/Puig_170714_nm_2629-1.jpeg\" alt=\"X Regata Puig Vela Classica_2017\" width=\"2000\" height=\"1119\" \/><\/p>\n<p><strong>La edici\u00f3n m\u00e1s disputada<\/strong><\/p>\n<p>La calidad de la flota y su alta competitividad dieron una buena muestra en esta edici\u00f3n, ya que cuatro de las cinco categor\u00edas comenzaban la \u00faltima y decisiva jornada con empate en los primeros puestos.<\/p>\n<p>El Moonbeam III volv\u00eda a inscribir su nombre, y ya van seis, en el palmar\u00e9s de la flota Big Boats que asiduamente compite en esta prestigiosa regata internacional. De nuevo su m\u00e1ximo rival fue el Moonbeam IV, que arrancaba con una victoria el primer d\u00eda, para ceder luego las dos victorias parciales al laureado ganador. El Cambria italiano, finalmente tercero, les present\u00f3 batalla, pero no puedo doblegarles en ninguna de las clasificaciones parciales. Otro tanto hizo el Xarifa 1927, quien debi\u00f3 conformarse con la cuarta plaza.<\/p>\n<p>El <strong>Guia<\/strong> defendi\u00f3 con \u00e9xito el t\u00edtulo en Cl\u00e1sicos 1, donde destacaba el estreno de<strong> Il Moro di Venezia.<\/strong> Pese a imponerse con claridad en la primera prueba, el debutante perdi\u00f3 fuelle mientras el <strong>Guia<\/strong> le empataba tras la segunda manga y le doblegaba en la tercera y \u00faltima prueba. Tercero fue otro debutante en Barcelona, el franc\u00e9s <strong>Saggitarius,<\/strong> que con una tripulaci\u00f3n poco numerosa y con importante presencia femenina naveg\u00f3 muy bien en su estreno, demostrando su buen hacer. Gracias a vencer la \u00faltima prueba, el <strong>Corsario II<\/strong> puso ser cuarto tras superar al <strong>Samarkand.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4851\" src=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2018\/04\/Puig_170715_nm_3141.jpeg\" alt=\"\u00a9Martinez StudioX Regata Puig Vela Classica\" width=\"2000\" height=\"1107\" \/><\/p>\n<p>En Cl\u00e1sicos 2, el <strong>Alba<\/strong> tambi\u00e9n se hac\u00eda con su sexto trofeo de la Puig Vela Cl\u00e0ssica Barcelona, en el particular duelo que mantiene con el <strong>Moonbeam III<\/strong> en aras de ser el m\u00e1s victorioso del palmar\u00e9s de la regata. Sin dar opciones en ninguna prueba, se impuso en los tres parciales. Tras \u00e9l compitieron estrechamente el <strong>Kanavel<\/strong> y el <strong>Margarita Estalindalamar,<\/strong> siendo \u00e9ste segundo en la clasificaci\u00f3n final al sorprender al<strong> Kanavel<\/strong> en la \u00faltima prueba y arrebatarle el subcampeonato. El <strong>Atrevido<\/strong> y el <strong>Diana<\/strong> completaban el Top 5 de la categor\u00eda.<\/p>\n<p>En la categor\u00eda \u00c9poca Cangreja los m\u00e1ximos honores fueron para el <strong>Kelpie of Falmouth<\/strong>, que decidi\u00f3 su victoria por un solo punto frente al <strong>Marigold,<\/strong> muy cerca de defender con \u00e9xito el t\u00edtulo logrado en la pasada edici\u00f3n. Tras los dos protagonistas se situaba c\u00f3modamente el <strong>Malabar X<\/strong>, mientras el <strong>Marigan<\/strong> era cuarto al superar por un punto al<strong> Gipsy y al Veronique.<\/strong><\/p>\n<p>El \u00c9poca Marconi <strong>Sonata<\/strong> tampoco pudo repetir como vencedor en la categor\u00eda m\u00e1s re\u00f1ida y numerosa de esta edici\u00f3n. Mientras en Big Boats, Cl\u00e1sicos 1 y \u00c9poca Cangreja part\u00edan igualados el \u00faltimo d\u00eda dos candidatos, en los Marconi lo hac\u00edan las tres embarcaciones <strong>Cippino, Fjord III y Argyll<\/strong>. Manteniendo un intenso duelo en la prueba final para dirimir el desempate, finalmente fue el argentino <strong>Cippino<\/strong> quien se impon\u00eda al uruguayo<strong> Fjord III<\/strong> y al brit\u00e1nico <strong>Argyll.<\/strong> Siguiendo al trio de cabeza se clasificaban el <strong>Circe, Oiseau de Feau y el Sonata.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4874\" src=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2017\/07\/Puig_170714_nm_1724.jpeg\" alt=\"\u00a9Martinez Studio X Regata Puig Vela Classica\" width=\"2000\" height=\"1228\" \/><\/p>\n<p><strong>Algunos de m\u00e1s de un siglo, otros \u201cs\u00f3lo\u201d cumplen 90 a\u00f1os<\/strong><\/p>\n<p>Esta d\u00e9cima edici\u00f3n supone un importante hito para el Gipsy de \u201cPetete\u201d Rubio, que celebra el 90 aniversario del barco. Fue la \u00fanica embarcaci\u00f3n de uso civil que se construy\u00f3 en el astillero Echevarrieta y Larrinaga (C\u00e1diz), que era de uso eminentemente militar. Durante la Guerra Civil actu\u00f3 como barco esp\u00eda para el bando nacional entre los cabos de Creus y La Nao. Todav\u00eda figuran en los palos marcas de metralla de las dos veces que fue tiroteado.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4876\" src=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2017\/07\/Puig_170714_nm_2648.jpeg\" alt=\"X Regata Puig Vela Classica_2017\" width=\"2000\" height=\"1185\" \/> <\/p>\n<p>\u201cEl barco lo compr\u00f3 mi familia en 1951. Eran muy aficionados a la vela y buscaban un velero con estilo y que navegara bien. Vieron el Gipsy, les gust\u00f3 y decidieron comprarlo\u201d, asegura Petete Rubio y a\u00f1ade \u201ces una goleta singular, con muchas historias en sus maderas. Lo restauramos en 1969 y en 2006, preservando en ambas reformas las dos balas que encontramos incrustadas en el casco.\u201d<\/p>\n<p>El Gipsy ha participado ha participado en las diez ediciones de la regata Puig Vela Cl\u00e0ssica Barcelona. \u201cNuestra idea es aprovechar esta regata para festejar el aniversario del Gipsy y, por supuesto, nos gustar\u00eda ganar este a\u00f1o, ser\u00eda la guinda del pastel. Adem\u00e1s, como detalle de la efem\u00e9ride, la organizaci\u00f3n ha concedido el dorsal 90 al Gipsy para sumarse a la celebraci\u00f3n\u201d cuenta Petete.<\/p>\n<p><strong>Una representaci\u00f3n italiana de excepci\u00f3n: Il Moro di Venezia I y la Armada Italiana<\/strong><\/p>\n<p>Entre los veleros que debutan este a\u00f1o en la regata Puig Vela Cl\u00e0ssica Barcelona, destacan los italianos Il Moro di Venezia I y el buque de la armada, el Corsario II.<\/p>\n<p>Il Moro di Venezia I fue el primer barco de la legendaria saga \u201cIl Moro di Venezia\u201d del magnate italiano Ra\u00fal Gardini, que puso a Italia en lo m\u00e1s alto de la vela mundial con una serie de veleros ultra competitivos y ganadores a\u00f1o tras a\u00f1o de algunas de las pruebas m\u00e1s destacadas del circuito internacional, adem\u00e1s de participar con \u00e9xito alcanzando la final de la Copa Am\u00e9rica.<\/p>\n<p>En su estreno en la Puig Vela Cl\u00e0ssica Barcelona, Humberto Zocoa Rangome di Montelupo, navegante y vela mayor del barco, cuenta que \u201cconoc\u00eda muy bien y me encantaba esta regata tras regatear muchos a\u00f1os a bordo del Amorita y del Peter y no dejaba de insistirle a mis compa\u00f1eros de Il Moro di Venezia que ten\u00edamos que competir aqu\u00ed. Este a\u00f1o por fin lo he conseguido y no puedo estar m\u00e1s contento. Disponer de este maravilloso velero ganador de tantas pruebas en la costa barcelonesa es un verdadero honor.\u201d A\u00f1ade que \u201cen Il Moro di Venezia ante todo somos un gran grupo de amigos, muy coordinados y estamos muy satisfechos de estar empatados en el liderato de la categor\u00eda de Cl\u00e1sicos 1\u201d. En cuanto a los dos d\u00edas de regata Humberto asegura que \u201cpara nosotros han resultado muy positivos gracias al magn\u00edfico viento del que hemos disfrutado y que tan bien va para nuestro velero\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4875\" src=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2017\/07\/MG_5379-scaled.jpeg\" alt=\"_MG_5379\" width=\"3347\" height=\"2232\" \/><\/p>\n<p>Por su parte, el Corsario II, fue dise\u00f1ado y construido para la Academia Naval italiana. Este velero compite en las mejores regatas del Mediterr\u00e1neo y sirve a su vez de barco de entrenamiento por los cadetes de la Academia naval de Livorno. Comisionado por la misma marina italiana y capitaneado por Simone Giusti, el Corsario II navega por primera vez en aguas barcelonesas. \u201cHace tres a\u00f1os vinieron nuestros compa\u00f1eros del Stella Polare y nosotros ten\u00edamos ya muchas ganas de hacerlo\u201d, asegura Giusti y a\u00f1ade que \u201cLa Puig Vela Cl\u00e0ssica Barcelona nos est\u00e1 resultando una regata muy bonita, con mucha ola y viento, lo que hace muy exigente la navegaci\u00f3n. Si a esto le a\u00f1adimos el que se dispute en una ciudad como Barcelona, esta competici\u00f3n es irresistible para repetir a\u00f1o tras a\u00f1o\u201d.<\/p>\n<p>Con respecto a su velero, Simone afirma que \u201cal tratarse de un barco escuela de la marina, la tripulaci\u00f3n est\u00e1 en constante cambio. En este velero cl\u00e1sico, donde todo es manual, requiere mucha fuerza, constancia y dedicaci\u00f3n, por lo que supone una formaci\u00f3n extraordinaria para nuestros marines\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cippino, Guia, Alba, Kelpie of Falmouth y Moonbeam III se proclamaron vencedores en una de las finales m\u00e1s re\u00f1idas de la historia de la regata, que comenz\u00f3 con empates en cuatro de las cinco categor\u00edas M\u00e1s de 50 barcos de 12 pa\u00edses y 600 navegantes han competido en la edici\u00f3n del 10 aniversario de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7155,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"class_list":["post-4869","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La regata Puig Vela Cl\u00e0ssica Barcelona se consolida en su d\u00e9cimo aniversario como uno de los circuitos de vela cl\u00e1sica m\u00e1s importantes del Mediterr\u00e1neo - Puig Vela Cl\u00e0ssica Barcelona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-barcelona-se-consolida-en-su-decimo-aniversario-como-uno-de-los-circuitos-de-vela-clasica-mas-importantes-del-mediterraneo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La regata Puig Vela Cl\u00e0ssica Barcelona se consolida en su d\u00e9cimo aniversario como uno de los circuitos de vela cl\u00e1sica m\u00e1s importantes del Mediterr\u00e1neo - Puig Vela Cl\u00e0ssica Barcelona\" \/>\n<meta property=\"og:description\" content=\"Cippino, Guia, Alba, Kelpie of Falmouth y Moonbeam III se proclamaron vencedores en una de las finales m\u00e1s re\u00f1idas de la historia de la regata, que comenz\u00f3 con empates en cuatro de las cinco categor\u00edas M\u00e1s de 50 barcos de 12 pa\u00edses y 600 navegantes han competido en la edici\u00f3n del 10 aniversario de la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-barcelona-se-consolida-en-su-decimo-aniversario-como-uno-de-los-circuitos-de-vela-clasica-mas-importantes-del-mediterraneo\/\" \/>\n<meta property=\"og:site_name\" content=\"Puig Vela Cl\u00e0ssica Barcelona\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-21T09:33:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-21T10:56:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2017\/07\/Puig_170714_nm_2629-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1119\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"velaclassica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"velaclassica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-barcelona-se-consolida-en-su-decimo-aniversario-como-uno-de-los-circuitos-de-vela-clasica-mas-importantes-del-mediterraneo\/\",\"url\":\"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-barcelona-se-consolida-en-su-decimo-aniversario-como-uno-de-los-circuitos-de-vela-clasica-mas-importantes-del-mediterraneo\/\",\"name\":\"La regata Puig Vela Cl\u00e0ssica Barcelona se consolida en su d\u00e9cimo aniversario como uno de los circuitos de vela cl\u00e1sica m\u00e1s importantes del Mediterr\u00e1neo - Puig Vela Cl\u00e0ssica Barcelona\",\"isPartOf\":{\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-barcelona-se-consolida-en-su-decimo-aniversario-como-uno-de-los-circuitos-de-vela-clasica-mas-importantes-del-mediterraneo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-barcelona-se-consolida-en-su-decimo-aniversario-como-uno-de-los-circuitos-de-vela-clasica-mas-importantes-del-mediterraneo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2017\/07\/Puig_170714_nm_2629-1.jpeg\",\"datePublished\":\"2017-07-21T09:33:45+00:00\",\"dateModified\":\"2024-01-21T10:56:10+00:00\",\"author\":{\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/0f1f6cd6f23050a19e91a3003de34c7e\"},\"breadcrumb\":{\"@id\":\"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-barcelona-se-consolida-en-su-decimo-aniversario-como-uno-de-los-circuitos-de-vela-clasica-mas-importantes-del-mediterraneo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-barcelona-se-consolida-en-su-decimo-aniversario-como-uno-de-los-circuitos-de-vela-clasica-mas-importantes-del-mediterraneo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-barcelona-se-consolida-en-su-decimo-aniversario-como-uno-de-los-circuitos-de-vela-clasica-mas-importantes-del-mediterraneo\/#primaryimage\",\"url\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2017\/07\/Puig_170714_nm_2629-1.jpeg\",\"contentUrl\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2017\/07\/Puig_170714_nm_2629-1.jpeg\",\"width\":2000,\"height\":1119},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-barcelona-se-consolida-en-su-decimo-aniversario-como-uno-de-los-circuitos-de-vela-clasica-mas-importantes-del-mediterraneo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mail.puigvelaclasica.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La regata Puig Vela Cl\u00e0ssica Barcelona se consolida en su d\u00e9cimo aniversario como uno de los circuitos de vela cl\u00e1sica m\u00e1s importantes del Mediterr\u00e1neo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#website\",\"url\":\"https:\/\/www.puigvelaclassicabarcelona.com\/\",\"name\":\"Puig Vela Cl\u00e0ssica Barcelona\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.puigvelaclassicabarcelona.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/0f1f6cd6f23050a19e91a3003de34c7e\",\"name\":\"velaclassica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/18a97ff0e5d67038bad233b79246a7f922424d224871d207487c88e471e664c2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/18a97ff0e5d67038bad233b79246a7f922424d224871d207487c88e471e664c2?s=96&d=mm&r=g\",\"caption\":\"velaclassica\"},\"sameAs\":[\"https:\/\/puigvelaclassica.com\/\"],\"url\":\"https:\/\/puigvelaclassica.com\/es\/author\/velaclassica\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La regata Puig Vela Cl\u00e0ssica Barcelona se consolida en su d\u00e9cimo aniversario como uno de los circuitos de vela cl\u00e1sica m\u00e1s importantes del Mediterr\u00e1neo - Puig Vela Cl\u00e0ssica Barcelona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-barcelona-se-consolida-en-su-decimo-aniversario-como-uno-de-los-circuitos-de-vela-clasica-mas-importantes-del-mediterraneo\/","og_locale":"es_ES","og_type":"article","og_title":"La regata Puig Vela Cl\u00e0ssica Barcelona se consolida en su d\u00e9cimo aniversario como uno de los circuitos de vela cl\u00e1sica m\u00e1s importantes del Mediterr\u00e1neo - Puig Vela Cl\u00e0ssica Barcelona","og_description":"Cippino, Guia, Alba, Kelpie of Falmouth y Moonbeam III se proclamaron vencedores en una de las finales m\u00e1s re\u00f1idas de la historia de la regata, que comenz\u00f3 con empates en cuatro de las cinco categor\u00edas M\u00e1s de 50 barcos de 12 pa\u00edses y 600 navegantes han competido en la edici\u00f3n del 10 aniversario de la [&hellip;]","og_url":"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-barcelona-se-consolida-en-su-decimo-aniversario-como-uno-de-los-circuitos-de-vela-clasica-mas-importantes-del-mediterraneo\/","og_site_name":"Puig Vela Cl\u00e0ssica Barcelona","article_published_time":"2017-07-21T09:33:45+00:00","article_modified_time":"2024-01-21T10:56:10+00:00","og_image":[{"width":2000,"height":1119,"url":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2017\/07\/Puig_170714_nm_2629-1.jpeg","type":"image\/jpeg"}],"author":"velaclassica","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"velaclassica","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-barcelona-se-consolida-en-su-decimo-aniversario-como-uno-de-los-circuitos-de-vela-clasica-mas-importantes-del-mediterraneo\/","url":"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-barcelona-se-consolida-en-su-decimo-aniversario-como-uno-de-los-circuitos-de-vela-clasica-mas-importantes-del-mediterraneo\/","name":"La regata Puig Vela Cl\u00e0ssica Barcelona se consolida en su d\u00e9cimo aniversario como uno de los circuitos de vela cl\u00e1sica m\u00e1s importantes del Mediterr\u00e1neo - Puig Vela Cl\u00e0ssica Barcelona","isPartOf":{"@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-barcelona-se-consolida-en-su-decimo-aniversario-como-uno-de-los-circuitos-de-vela-clasica-mas-importantes-del-mediterraneo\/#primaryimage"},"image":{"@id":"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-barcelona-se-consolida-en-su-decimo-aniversario-como-uno-de-los-circuitos-de-vela-clasica-mas-importantes-del-mediterraneo\/#primaryimage"},"thumbnailUrl":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2017\/07\/Puig_170714_nm_2629-1.jpeg","datePublished":"2017-07-21T09:33:45+00:00","dateModified":"2024-01-21T10:56:10+00:00","author":{"@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/0f1f6cd6f23050a19e91a3003de34c7e"},"breadcrumb":{"@id":"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-barcelona-se-consolida-en-su-decimo-aniversario-como-uno-de-los-circuitos-de-vela-clasica-mas-importantes-del-mediterraneo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-barcelona-se-consolida-en-su-decimo-aniversario-como-uno-de-los-circuitos-de-vela-clasica-mas-importantes-del-mediterraneo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-barcelona-se-consolida-en-su-decimo-aniversario-como-uno-de-los-circuitos-de-vela-clasica-mas-importantes-del-mediterraneo\/#primaryimage","url":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2017\/07\/Puig_170714_nm_2629-1.jpeg","contentUrl":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2017\/07\/Puig_170714_nm_2629-1.jpeg","width":2000,"height":1119},{"@type":"BreadcrumbList","@id":"https:\/\/puigvelaclassica.com\/es\/la-regata-puig-vela-classica-barcelona-se-consolida-en-su-decimo-aniversario-como-uno-de-los-circuitos-de-vela-clasica-mas-importantes-del-mediterraneo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mail.puigvelaclasica.com\/es\/"},{"@type":"ListItem","position":2,"name":"La regata Puig Vela Cl\u00e0ssica Barcelona se consolida en su d\u00e9cimo aniversario como uno de los circuitos de vela cl\u00e1sica m\u00e1s importantes del Mediterr\u00e1neo"}]},{"@type":"WebSite","@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#website","url":"https:\/\/www.puigvelaclassicabarcelona.com\/","name":"Puig Vela Cl\u00e0ssica Barcelona","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.puigvelaclassicabarcelona.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/0f1f6cd6f23050a19e91a3003de34c7e","name":"velaclassica","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/18a97ff0e5d67038bad233b79246a7f922424d224871d207487c88e471e664c2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/18a97ff0e5d67038bad233b79246a7f922424d224871d207487c88e471e664c2?s=96&d=mm&r=g","caption":"velaclassica"},"sameAs":["https:\/\/puigvelaclassica.com\/"],"url":"https:\/\/puigvelaclassica.com\/es\/author\/velaclassica\/"}]}},"_links":{"self":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/posts\/4869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/comments?post=4869"}],"version-history":[{"count":2,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/posts\/4869\/revisions"}],"predecessor-version":[{"id":7168,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/posts\/4869\/revisions\/7168"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/media\/7155"}],"wp:attachment":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/media?parent=4869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/categories?post=4869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}