{"id":4941,"date":"2018-04-24T14:46:43","date_gmt":"2018-04-24T14:46:43","guid":{"rendered":"http:\/\/www.puigvelaclassica.com\/?p=4941"},"modified":"2024-01-21T10:50:35","modified_gmt":"2024-01-21T10:50:35","slug":"egata-puig-vela-classica-barcelona-xi-edicion-11-al-14-julio","status":"publish","type":"post","link":"https:\/\/puigvelaclassica.com\/es\/egata-puig-vela-classica-barcelona-xi-edicion-11-al-14-julio\/","title":{"rendered":"La regata Puig Vela Cl\u00e0ssica Barcelona celebrar\u00e1 su XI Edici\u00f3n del 11 al 14 de julio"},"content":{"rendered":"<ul>\n<li>Cerca de medio centenar de embarcaciones de todo el mundo se reunir\u00e1n en aguas del Real Club N\u00e1utico de Barcelona<\/li>\n<\/ul>\n<p>Cerca de medio centenar de veleros participar\u00e1n en la<strong> XI edici\u00f3n de la regata Puig Vela Cl\u00e0ssica Barcelona del 11 al 14 de julio<\/strong>, una cita obligada para los amantes de los deportes n\u00e1uticos organizada por Puig y el Real Club N\u00e1utico de Barcelona. Esta competici\u00f3n, que se ha consolidado como uno de los eventos de mayor prestigio internacional de la navegaci\u00f3n cl\u00e1sica y de \u00e9poca, reunir\u00e1 los barcos m\u00e1s bellos del mundo procedentes de Espa\u00f1a y de otros pa\u00edses europeos como Alemania, Francia, Holanda, Inglaterra, Italia, as\u00ed como de Estados Unidos y Argentina, entre otros.<\/p>\n<p>Veleros exclusivos y con una larga historia como el <a href=\"http:\/\/www.puigvelaclassica.com\/es\/llegendes\/alba-2\/\" target=\"_blank\" rel=\"noopener\">Alba<\/a>, el <a href=\"http:\/\/www.puigvelaclassica.com\/es\/llegendes\/kelpie-of-falmouth-2\/\" target=\"_blank\" rel=\"noopener\">Kelpie of Falmouth<\/a> o el <a href=\"http:\/\/www.puigvelaclassica.com\/es\/llegendes\/moonbeam-iii-3\/\" target=\"_blank\" rel=\"noopener\">Moonbeam III,<\/a> que se proclamaron vencedores en la edici\u00f3n anterior, surcar\u00e1n de nuevo el Mediterr\u00e1neo en esta XI edici\u00f3n de la regata Puig Vela Cl\u00e0ssica Barcelona. Todas las embarcaciones participantes, muchas de ellas con m\u00e1s de cien a\u00f1os de historia, conservan su est\u00e9tica original, lo que las convierte en aut\u00e9nticas joyas de la navegaci\u00f3n, propias de un museo flotante.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4851\" src=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2018\/04\/Puig_170715_nm_3141.jpeg\" alt=\"\u00a9Martinez StudioX Regata Puig Vela Classica\" width=\"2000\" height=\"1107\" \/><\/p>\n<p>Muchos de ellos han sido testigos de acontecimientos hist\u00f3ricos, como el <a href=\"http:\/\/www.puigvelaclassica.com\/es\/llegendes\/moonbeam-iv-3\/\" target=\"_blank\" rel=\"noopener\">Moonbeam IV<\/a>, donde los pr\u00edncipes Rainiero y Grace de M\u00f3naco pasaron su luna de miel; el Manitou, en el que naveg\u00f3 el presidente de EE. UU John F. Kennedy; o el Islander, que ostenta el r\u00e9cord de navegaci\u00f3n en solitario al dar la vuelta al mundo en tres ocasiones.<\/p>\n<p>Barcelona es de los pocos enclaves del mundo, como Antigua, Newport o Cannes, que tiene la exclusividad de acoger regatas de barcos cl\u00e1sicos. Desde siempre, tanto los ciudadanos como los turistas que visitan la ciudad durante la segunda semana de julio se han volcado con la regata Puig Vela Cl\u00e0ssica Barcelona. Un espect\u00e1culo \u00fanico que se puede contemplar desde diferentes escenarios emblem\u00e1ticos de la ciudad como la playa de la Barceloneta, el Port Ol\u00edmpic o el Port Vell.<\/p>\n<p>La regata Puig Vela Cl\u00e0ssica Barcelona es ya una cita imprescindible en el calendario de regatas y ha conseguido afianzarse tanto en el \u00e1mbito nacional como internacional. El evento se enmarca en el calendario oficial de la Real Federaci\u00f3n Espa\u00f1ola de Vela (RFEV) y es puntuable para el Campeonato de Espa\u00f1a de Barcos Cl\u00e1sicos y de \u00c9poca de 2018 y para el VIII Trofeo Mare Nostrum.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cerca de medio centenar de embarcaciones de todo el mundo se reunir\u00e1n en aguas del Real Club N\u00e1utico de Barcelona Cerca de medio centenar de veleros participar\u00e1n en la XI edici\u00f3n de la regata Puig Vela Cl\u00e0ssica Barcelona del 11 al 14 de julio, una cita obligada para los amantes de los deportes n\u00e1uticos organizada [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7150,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"class_list":["post-4941","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La regata Puig Vela Cl\u00e0ssica Barcelona celebrar\u00e1 su XI Edici\u00f3n del 11 al 14 de julio - Puig Vela Cl\u00e0ssica Barcelona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/puigvelaclassica.com\/es\/egata-puig-vela-classica-barcelona-xi-edicion-11-al-14-julio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La regata Puig Vela Cl\u00e0ssica Barcelona celebrar\u00e1 su XI Edici\u00f3n del 11 al 14 de julio - Puig Vela Cl\u00e0ssica Barcelona\" \/>\n<meta property=\"og:description\" content=\"Cerca de medio centenar de embarcaciones de todo el mundo se reunir\u00e1n en aguas del Real Club N\u00e1utico de Barcelona Cerca de medio centenar de veleros participar\u00e1n en la XI edici\u00f3n de la regata Puig Vela Cl\u00e0ssica Barcelona del 11 al 14 de julio, una cita obligada para los amantes de los deportes n\u00e1uticos organizada [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/puigvelaclassica.com\/es\/egata-puig-vela-classica-barcelona-xi-edicion-11-al-14-julio\/\" \/>\n<meta property=\"og:site_name\" content=\"Puig Vela Cl\u00e0ssica Barcelona\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-24T14:46:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-21T10:50:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2018\/04\/Puig_170715_nm_3141.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1107\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"velaclassica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"velaclassica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/puigvelaclassica.com\/es\/egata-puig-vela-classica-barcelona-xi-edicion-11-al-14-julio\/\",\"url\":\"https:\/\/puigvelaclassica.com\/es\/egata-puig-vela-classica-barcelona-xi-edicion-11-al-14-julio\/\",\"name\":\"La regata Puig Vela Cl\u00e0ssica Barcelona celebrar\u00e1 su XI Edici\u00f3n del 11 al 14 de julio - Puig Vela Cl\u00e0ssica Barcelona\",\"isPartOf\":{\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/puigvelaclassica.com\/es\/egata-puig-vela-classica-barcelona-xi-edicion-11-al-14-julio\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/puigvelaclassica.com\/es\/egata-puig-vela-classica-barcelona-xi-edicion-11-al-14-julio\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2018\/04\/Puig_170715_nm_3141.jpeg\",\"datePublished\":\"2018-04-24T14:46:43+00:00\",\"dateModified\":\"2024-01-21T10:50:35+00:00\",\"author\":{\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/0f1f6cd6f23050a19e91a3003de34c7e\"},\"breadcrumb\":{\"@id\":\"https:\/\/puigvelaclassica.com\/es\/egata-puig-vela-classica-barcelona-xi-edicion-11-al-14-julio\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/puigvelaclassica.com\/es\/egata-puig-vela-classica-barcelona-xi-edicion-11-al-14-julio\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/puigvelaclassica.com\/es\/egata-puig-vela-classica-barcelona-xi-edicion-11-al-14-julio\/#primaryimage\",\"url\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2018\/04\/Puig_170715_nm_3141.jpeg\",\"contentUrl\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2018\/04\/Puig_170715_nm_3141.jpeg\",\"width\":2000,\"height\":1107},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/puigvelaclassica.com\/es\/egata-puig-vela-classica-barcelona-xi-edicion-11-al-14-julio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mail.puigvelaclasica.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La regata Puig Vela Cl\u00e0ssica Barcelona celebrar\u00e1 su XI Edici\u00f3n del 11 al 14 de julio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#website\",\"url\":\"https:\/\/www.puigvelaclassicabarcelona.com\/\",\"name\":\"Puig Vela Cl\u00e0ssica Barcelona\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.puigvelaclassicabarcelona.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/0f1f6cd6f23050a19e91a3003de34c7e\",\"name\":\"velaclassica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/18a97ff0e5d67038bad233b79246a7f922424d224871d207487c88e471e664c2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/18a97ff0e5d67038bad233b79246a7f922424d224871d207487c88e471e664c2?s=96&d=mm&r=g\",\"caption\":\"velaclassica\"},\"sameAs\":[\"https:\/\/puigvelaclassica.com\/\"],\"url\":\"https:\/\/puigvelaclassica.com\/es\/author\/velaclassica\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La regata Puig Vela Cl\u00e0ssica Barcelona celebrar\u00e1 su XI Edici\u00f3n del 11 al 14 de julio - Puig Vela Cl\u00e0ssica Barcelona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/puigvelaclassica.com\/es\/egata-puig-vela-classica-barcelona-xi-edicion-11-al-14-julio\/","og_locale":"es_ES","og_type":"article","og_title":"La regata Puig Vela Cl\u00e0ssica Barcelona celebrar\u00e1 su XI Edici\u00f3n del 11 al 14 de julio - Puig Vela Cl\u00e0ssica Barcelona","og_description":"Cerca de medio centenar de embarcaciones de todo el mundo se reunir\u00e1n en aguas del Real Club N\u00e1utico de Barcelona Cerca de medio centenar de veleros participar\u00e1n en la XI edici\u00f3n de la regata Puig Vela Cl\u00e0ssica Barcelona del 11 al 14 de julio, una cita obligada para los amantes de los deportes n\u00e1uticos organizada [&hellip;]","og_url":"https:\/\/puigvelaclassica.com\/es\/egata-puig-vela-classica-barcelona-xi-edicion-11-al-14-julio\/","og_site_name":"Puig Vela Cl\u00e0ssica Barcelona","article_published_time":"2018-04-24T14:46:43+00:00","article_modified_time":"2024-01-21T10:50:35+00:00","og_image":[{"width":2000,"height":1107,"url":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2018\/04\/Puig_170715_nm_3141.jpeg","type":"image\/jpeg"}],"author":"velaclassica","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"velaclassica","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/puigvelaclassica.com\/es\/egata-puig-vela-classica-barcelona-xi-edicion-11-al-14-julio\/","url":"https:\/\/puigvelaclassica.com\/es\/egata-puig-vela-classica-barcelona-xi-edicion-11-al-14-julio\/","name":"La regata Puig Vela Cl\u00e0ssica Barcelona celebrar\u00e1 su XI Edici\u00f3n del 11 al 14 de julio - Puig Vela Cl\u00e0ssica Barcelona","isPartOf":{"@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/puigvelaclassica.com\/es\/egata-puig-vela-classica-barcelona-xi-edicion-11-al-14-julio\/#primaryimage"},"image":{"@id":"https:\/\/puigvelaclassica.com\/es\/egata-puig-vela-classica-barcelona-xi-edicion-11-al-14-julio\/#primaryimage"},"thumbnailUrl":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2018\/04\/Puig_170715_nm_3141.jpeg","datePublished":"2018-04-24T14:46:43+00:00","dateModified":"2024-01-21T10:50:35+00:00","author":{"@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/0f1f6cd6f23050a19e91a3003de34c7e"},"breadcrumb":{"@id":"https:\/\/puigvelaclassica.com\/es\/egata-puig-vela-classica-barcelona-xi-edicion-11-al-14-julio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/puigvelaclassica.com\/es\/egata-puig-vela-classica-barcelona-xi-edicion-11-al-14-julio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/puigvelaclassica.com\/es\/egata-puig-vela-classica-barcelona-xi-edicion-11-al-14-julio\/#primaryimage","url":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2018\/04\/Puig_170715_nm_3141.jpeg","contentUrl":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2018\/04\/Puig_170715_nm_3141.jpeg","width":2000,"height":1107},{"@type":"BreadcrumbList","@id":"https:\/\/puigvelaclassica.com\/es\/egata-puig-vela-classica-barcelona-xi-edicion-11-al-14-julio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mail.puigvelaclasica.com\/es\/"},{"@type":"ListItem","position":2,"name":"La regata Puig Vela Cl\u00e0ssica Barcelona celebrar\u00e1 su XI Edici\u00f3n del 11 al 14 de julio"}]},{"@type":"WebSite","@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#website","url":"https:\/\/www.puigvelaclassicabarcelona.com\/","name":"Puig Vela Cl\u00e0ssica Barcelona","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.puigvelaclassicabarcelona.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/0f1f6cd6f23050a19e91a3003de34c7e","name":"velaclassica","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/18a97ff0e5d67038bad233b79246a7f922424d224871d207487c88e471e664c2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/18a97ff0e5d67038bad233b79246a7f922424d224871d207487c88e471e664c2?s=96&d=mm&r=g","caption":"velaclassica"},"sameAs":["https:\/\/puigvelaclassica.com\/"],"url":"https:\/\/puigvelaclassica.com\/es\/author\/velaclassica\/"}]}},"_links":{"self":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/posts\/4941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/comments?post=4941"}],"version-history":[{"count":1,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/posts\/4941\/revisions"}],"predecessor-version":[{"id":7153,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/posts\/4941\/revisions\/7153"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/media\/7150"}],"wp:attachment":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/media?parent=4941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/categories?post=4941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}