{"id":4997,"date":"2018-07-11T12:24:51","date_gmt":"2018-07-11T12:24:51","guid":{"rendered":"https:\/\/www.puigvelaclassica.com\/?p=4997"},"modified":"2024-01-21T10:46:00","modified_gmt":"2024-01-21T10:46:00","slug":"comienza-la-xi-edicion-de-la-puig-vela-classica-barcelona","status":"publish","type":"post","link":"https:\/\/puigvelaclassica.com\/es\/comienza-la-xi-edicion-de-la-puig-vela-classica-barcelona\/","title":{"rendered":"Comienza la XI edici\u00f3n de la Puig Vela Cl\u00e0ssica Barcelona"},"content":{"rendered":"<ul>\n<li>M\u00e1s de 40 barcos de 7 pa\u00edses representados y alrededor de 500 navegantes con un alt\u00edsimo nivel en competici\u00f3n se dan cita en Barcelona<\/li>\n<li>Es la cita anual de los barcos m\u00e1s elegantes y legendarios que ofrece un espect\u00e1culo n\u00e1utico lleno de tradici\u00f3n y esp\u00edritu deportivo<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Esta tarde da comienzo la XI regata Puig Vela Cl\u00e0ssica Barcelona que re\u00fane lo mejor de la vela cl\u00e1sica en aguas barcelonesas hasta el 14 de julio. Una cita obligada del calendario deportivo que esta edici\u00f3n congrega a m\u00e1s de 40 barcos cl\u00e1sicos, aut\u00e9nticas leyendas flotantes, que convierten la ciudad condal en el epicentro mundial de la vela cl\u00e1sica y de \u00e9poca.<\/p>\n<p>Desde hace unas horas los amarres del Club N\u00e1utico de Barcelona lucen en todo su esplendor y todo est\u00e1 listo para que ma\u00f1ana d\u00e9 comienzo la primera jornada de tres d\u00edas de competici\u00f3n, en el que cerca de 500 regatistas procedentes de Espa\u00f1a y pa\u00edses como Francia, Reino Unido, Italia, EE. UU., Suiza o Irlanda competir\u00e1n en las aguas de la capital catalana ofreciendo un espect\u00e1culo \u00fanico de la n\u00e1utica m\u00e1s pura.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4998\" src=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2018\/07\/Moonbeam-III_Ganador-Big-Boats-X-edicio\u0301n-Puig-Vela-Cla\u0300ssica-2.jpeg\" alt=\"Moonbeam III_Ganador Big Boats X edici\u00f3n Puig Vela Cl\u00e0ssica (2)\" width=\"1024\" height=\"669\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>El campo de regatas barcelon\u00e9s situado frente a sus playas, ser\u00e1 de nuevo el escenario de la Regata Puig Vela Cl\u00e0ssica. En su decimoprimera edici\u00f3n, la competici\u00f3n espa\u00f1ola de Barcos Cl\u00e1sicos y de \u00c9poca m\u00e1s prestigiosa, vuelve a contar con una participaci\u00f3n de lujo. Una cuarentena de barcos navegar\u00e1n agrupados en las categor\u00edas Cl\u00e1sicos, \u00c9poca y Big Boats, con un programa deportivo que prev\u00e9 la disputa de tres pruebas en el campo de regatas barcelon\u00e9s, situado frente a sus populares playas.<\/p>\n<p>Entre ellos no faltan cuatro de los cinco vencedores de la pasada edici\u00f3n: Alba (Cl\u00e1sicos 1), Moonbeam 3 (Big Boats), y Kelpie of Falmouth (\u00c9poca Cangreja) repiten su condici\u00f3n de favoritos, as\u00ed como Guia (Cl\u00e1sicos 2) cuya tripulaci\u00f3n quiere rendir un homenaje a su armador Ram\u00f3n Ros\u00e9s, fallecido recientemente tras una larga enfermedad que no le impidi\u00f3 ser protagonista de las \u00faltimas ediciones de esta regata. El importante car\u00e1cter internacional de la Puig Vela Cl\u00e0ssica se confirma con las 8 nacionalidades de la flota participante.<\/p>\n<p>El programa deportivo previsto comenzar\u00e1 ma\u00f1ana jueves a las 13 horas, momento previsto para el tiro de salida de la primera prueba, y que contempla sendas pruebas el viernes y s\u00e1bado a la misma hora. Un horario sujeto a las condiciones meteorol\u00f3gicas, que prev\u00e9n vientos moderados que soplar\u00e1n entre el Este y el Sur. Si parecen seguras unas altas temperaturas, que todav\u00eda exigir\u00e1n m\u00e1s a las tripulaciones.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2018\/07\/Kelpie_Ganador-epoca-Cangreja-X-edicion-Puig-Vela-Cla\u0300ssica.jpeg\" alt=\"Kelpie_Ganador epoca Cangreja X edicion Puig Vela Cl\u00e0ssica\" width=\"1024\" height=\"603\" class=\"alignnone size-full wp-image-5003\" \/><\/p>\n<p><strong>La vela cl\u00e1sica, la de \u00e9poca y tradici\u00f3n, protagonista de la XI regata Puig Vela Cl\u00e0ssica Barcelona<\/strong><\/p>\n<p>Muchas de las embarcaciones participantes en ediciones anteriores repiten este a\u00f1o, animadas tanto por las magn\u00edficas condiciones de las aguas del puerto barcelon\u00e9s, como por el alto nivel de la competici\u00f3n. Ser\u00e1n tres d\u00edas en los que los protagonistas ser\u00e1n goletas, sloop, ketch, cutter o yawl, verdaderas piezas de museo de los siglos XIX y XX, que impondr\u00e1n una gran pericia a sus tripulantes.<\/p>\n<p>M\u00e1s de 40 joyas de la n\u00e1utica como el Moonbeam IV de 1914, el Islander de 1937 o el Yanira de 1953 entre otros, navegar\u00e1n frente a las playas barcelonesas en recorridos de tri\u00e1ngulo o pruebas costeras a lo largo de un circuito balizado.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Una cita obligada para los turistas y ciudadanos de la ciudad condal<\/strong><\/p>\n<p>La Regata Puig Vela Cl\u00e0ssica Barcelona se ha convertido en un referente del turismo para la ciudad que cada a\u00f1o congrega m\u00e1s p\u00fablico atra\u00eddo por este espect\u00e1culo mar\u00edtimo, famoso por la belleza de su escenario y la riqueza hist\u00f3rica y cultural de su entorno. Puig convierte un a\u00f1o m\u00e1s, las aguas de la capital catalana en el epicentro de la n\u00e1utica cl\u00e1sica y re\u00fane joyas mar\u00edtimas y ente social y deportivo en la costa barcelonesa por su extraordinaria belleza y elegancia.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4999\" src=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2018\/07\/Guia_Ganador-Clasicos-1-X-edicion-Puig-Vela-Classica.jpeg\" alt=\"Guia_Ganador Clasicos 1 X edicion Puig Vela Classica\" width=\"1024\" height=\"659\" \/><\/p>\n<p>Este evento podr\u00e1 contemplarse desde diferentes emplazamientos como el Puerto Viejo o el Puerto Ol\u00edmpico, as\u00ed como desde las mismas playas de la Barceloneta o de Sant Miquel. Por otro lado, quienes dispongan de un barco propio o decidan alquilarlo, tendr\u00e1n el lujo de disfrutar de la cercan\u00eda de estas embarcaciones de leyenda en el mar.<\/p>\n<p>Y es que no hay otra capital del mundo que albergue una regata de barcos cl\u00e1sicos como la que acoge cada a\u00f1o Barcelona. Entre los destinos de ensue\u00f1o donde se celebran los eventos de veleros cl\u00e1sicos como Cannes, Antibes, Antigua, Newport o la Isla de Wight, tan s\u00f3lo uno de ellos es una capital de importancia y trascendencia internacional: Barcelona.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s de 40 barcos de 7 pa\u00edses representados y alrededor de 500 navegantes con un alt\u00edsimo nivel en competici\u00f3n se dan cita en Barcelona Es la cita anual de los barcos m\u00e1s elegantes y legendarios que ofrece un espect\u00e1culo n\u00e1utico lleno de tradici\u00f3n y esp\u00edritu deportivo &nbsp; Esta tarde da comienzo la XI regata Puig [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7129,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"class_list":["post-4997","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Comienza la XI edici\u00f3n de la Puig Vela Cl\u00e0ssica Barcelona - Puig Vela Cl\u00e0ssica Barcelona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/puigvelaclassica.com\/es\/comienza-la-xi-edicion-de-la-puig-vela-classica-barcelona\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comienza la XI edici\u00f3n de la Puig Vela Cl\u00e0ssica Barcelona - Puig Vela Cl\u00e0ssica Barcelona\" \/>\n<meta property=\"og:description\" content=\"M\u00e1s de 40 barcos de 7 pa\u00edses representados y alrededor de 500 navegantes con un alt\u00edsimo nivel en competici\u00f3n se dan cita en Barcelona Es la cita anual de los barcos m\u00e1s elegantes y legendarios que ofrece un espect\u00e1culo n\u00e1utico lleno de tradici\u00f3n y esp\u00edritu deportivo &nbsp; Esta tarde da comienzo la XI regata Puig [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/puigvelaclassica.com\/es\/comienza-la-xi-edicion-de-la-puig-vela-classica-barcelona\/\" \/>\n<meta property=\"og:site_name\" content=\"Puig Vela Cl\u00e0ssica Barcelona\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-11T12:24:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-21T10:46:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2018\/07\/xipuigvelaclassica.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1133\" \/>\n\t<meta property=\"og:image:height\" content=\"692\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"velaclassica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"velaclassica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/puigvelaclassica.com\/es\/comienza-la-xi-edicion-de-la-puig-vela-classica-barcelona\/\",\"url\":\"https:\/\/puigvelaclassica.com\/es\/comienza-la-xi-edicion-de-la-puig-vela-classica-barcelona\/\",\"name\":\"Comienza la XI edici\u00f3n de la Puig Vela Cl\u00e0ssica Barcelona - Puig Vela Cl\u00e0ssica Barcelona\",\"isPartOf\":{\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/puigvelaclassica.com\/es\/comienza-la-xi-edicion-de-la-puig-vela-classica-barcelona\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/puigvelaclassica.com\/es\/comienza-la-xi-edicion-de-la-puig-vela-classica-barcelona\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2018\/07\/xipuigvelaclassica.png\",\"datePublished\":\"2018-07-11T12:24:51+00:00\",\"dateModified\":\"2024-01-21T10:46:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/0f1f6cd6f23050a19e91a3003de34c7e\"},\"breadcrumb\":{\"@id\":\"https:\/\/puigvelaclassica.com\/es\/comienza-la-xi-edicion-de-la-puig-vela-classica-barcelona\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/puigvelaclassica.com\/es\/comienza-la-xi-edicion-de-la-puig-vela-classica-barcelona\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/puigvelaclassica.com\/es\/comienza-la-xi-edicion-de-la-puig-vela-classica-barcelona\/#primaryimage\",\"url\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2018\/07\/xipuigvelaclassica.png\",\"contentUrl\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2018\/07\/xipuigvelaclassica.png\",\"width\":1133,\"height\":692},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/puigvelaclassica.com\/es\/comienza-la-xi-edicion-de-la-puig-vela-classica-barcelona\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mail.puigvelaclasica.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comienza la XI edici\u00f3n de la Puig Vela Cl\u00e0ssica Barcelona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#website\",\"url\":\"https:\/\/www.puigvelaclassicabarcelona.com\/\",\"name\":\"Puig Vela Cl\u00e0ssica Barcelona\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.puigvelaclassicabarcelona.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/0f1f6cd6f23050a19e91a3003de34c7e\",\"name\":\"velaclassica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/18a97ff0e5d67038bad233b79246a7f922424d224871d207487c88e471e664c2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/18a97ff0e5d67038bad233b79246a7f922424d224871d207487c88e471e664c2?s=96&d=mm&r=g\",\"caption\":\"velaclassica\"},\"sameAs\":[\"https:\/\/puigvelaclassica.com\/\"],\"url\":\"https:\/\/puigvelaclassica.com\/es\/author\/velaclassica\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comienza la XI edici\u00f3n de la Puig Vela Cl\u00e0ssica Barcelona - Puig Vela Cl\u00e0ssica Barcelona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/puigvelaclassica.com\/es\/comienza-la-xi-edicion-de-la-puig-vela-classica-barcelona\/","og_locale":"es_ES","og_type":"article","og_title":"Comienza la XI edici\u00f3n de la Puig Vela Cl\u00e0ssica Barcelona - Puig Vela Cl\u00e0ssica Barcelona","og_description":"M\u00e1s de 40 barcos de 7 pa\u00edses representados y alrededor de 500 navegantes con un alt\u00edsimo nivel en competici\u00f3n se dan cita en Barcelona Es la cita anual de los barcos m\u00e1s elegantes y legendarios que ofrece un espect\u00e1culo n\u00e1utico lleno de tradici\u00f3n y esp\u00edritu deportivo &nbsp; Esta tarde da comienzo la XI regata Puig [&hellip;]","og_url":"https:\/\/puigvelaclassica.com\/es\/comienza-la-xi-edicion-de-la-puig-vela-classica-barcelona\/","og_site_name":"Puig Vela Cl\u00e0ssica Barcelona","article_published_time":"2018-07-11T12:24:51+00:00","article_modified_time":"2024-01-21T10:46:00+00:00","og_image":[{"width":1133,"height":692,"url":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2018\/07\/xipuigvelaclassica.png","type":"image\/png"}],"author":"velaclassica","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"velaclassica","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/puigvelaclassica.com\/es\/comienza-la-xi-edicion-de-la-puig-vela-classica-barcelona\/","url":"https:\/\/puigvelaclassica.com\/es\/comienza-la-xi-edicion-de-la-puig-vela-classica-barcelona\/","name":"Comienza la XI edici\u00f3n de la Puig Vela Cl\u00e0ssica Barcelona - Puig Vela Cl\u00e0ssica Barcelona","isPartOf":{"@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/puigvelaclassica.com\/es\/comienza-la-xi-edicion-de-la-puig-vela-classica-barcelona\/#primaryimage"},"image":{"@id":"https:\/\/puigvelaclassica.com\/es\/comienza-la-xi-edicion-de-la-puig-vela-classica-barcelona\/#primaryimage"},"thumbnailUrl":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2018\/07\/xipuigvelaclassica.png","datePublished":"2018-07-11T12:24:51+00:00","dateModified":"2024-01-21T10:46:00+00:00","author":{"@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/0f1f6cd6f23050a19e91a3003de34c7e"},"breadcrumb":{"@id":"https:\/\/puigvelaclassica.com\/es\/comienza-la-xi-edicion-de-la-puig-vela-classica-barcelona\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/puigvelaclassica.com\/es\/comienza-la-xi-edicion-de-la-puig-vela-classica-barcelona\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/puigvelaclassica.com\/es\/comienza-la-xi-edicion-de-la-puig-vela-classica-barcelona\/#primaryimage","url":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2018\/07\/xipuigvelaclassica.png","contentUrl":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2018\/07\/xipuigvelaclassica.png","width":1133,"height":692},{"@type":"BreadcrumbList","@id":"https:\/\/puigvelaclassica.com\/es\/comienza-la-xi-edicion-de-la-puig-vela-classica-barcelona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mail.puigvelaclasica.com\/es\/"},{"@type":"ListItem","position":2,"name":"Comienza la XI edici\u00f3n de la Puig Vela Cl\u00e0ssica Barcelona"}]},{"@type":"WebSite","@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#website","url":"https:\/\/www.puigvelaclassicabarcelona.com\/","name":"Puig Vela Cl\u00e0ssica Barcelona","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.puigvelaclassicabarcelona.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/0f1f6cd6f23050a19e91a3003de34c7e","name":"velaclassica","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/18a97ff0e5d67038bad233b79246a7f922424d224871d207487c88e471e664c2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/18a97ff0e5d67038bad233b79246a7f922424d224871d207487c88e471e664c2?s=96&d=mm&r=g","caption":"velaclassica"},"sameAs":["https:\/\/puigvelaclassica.com\/"],"url":"https:\/\/puigvelaclassica.com\/es\/author\/velaclassica\/"}]}},"_links":{"self":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/posts\/4997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/comments?post=4997"}],"version-history":[{"count":1,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/posts\/4997\/revisions"}],"predecessor-version":[{"id":7138,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/posts\/4997\/revisions\/7138"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/media\/7129"}],"wp:attachment":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/media?parent=4997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/categories?post=4997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}