{"id":5328,"date":"2019-07-11T18:11:33","date_gmt":"2019-07-11T18:11:33","guid":{"rendered":"https:\/\/www.puigvelaclassica.com\/?p=5328"},"modified":"2024-01-20T13:37:17","modified_gmt":"2024-01-20T13:37:17","slug":"un-mar-y-un-viento-de-lujo-en-la-primera-jornada-de-la-regata-puig-vela-classica","status":"publish","type":"post","link":"https:\/\/puigvelaclassica.com\/es\/un-mar-y-un-viento-de-lujo-en-la-primera-jornada-de-la-regata-puig-vela-classica\/","title":{"rendered":"Un mar y un viento de lujo en la primera jornada  de la regata Puig Vela Cl\u00e0ssica"},"content":{"rendered":"<p>&nbsp;<\/p>\n<ul>\n<li><strong>El viento de garb\u00ed, y un recorrido junto a las playas han propiciado las envidiables condiciones de navegaci\u00f3n<\/strong><\/li>\n<li><strong>Turistas y barceloneses se han congregado en zonas emblem\u00e1ticas como el\u00a0Port Vell, las playas de la\u00a0Barceloneta\u00a0y\u00a0Sant Miquel para contemplar este espect\u00e1culo \u00fanico que une arte y deporte<\/strong><\/li>\n<li><strong>Guia, Argos, Moonbeam of Fife, Marigold y Cippino se han impuesto en la\u00a0primera jornada de la regata Puig Vela Cl\u00e0ssica<\/strong><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">La regata Puig Vela Cl\u00e0ssica, uno de los principales referentes de la vela cl\u00e1sica y de \u00e9poca del Mediterr\u00e1neo, ha comenzado hoy en aguas del Real Club N\u00e1utico de Barcelona (RCNB). M\u00e1s de 500 regatistas en 44 embarcaciones han participado en uno de los espect\u00e1culos marineros m\u00e1s bellos de la n\u00e1utica internacional.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5314\" src=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2019\/07\/I-jornada-de-la-XII-edicio\u0301n-regata-Puig-Vela-Cla\u0300ssica-1.jpeg\" alt=\"\" width=\"2500\" height=\"1742\" \/><\/p>\n<p><span style=\"font-weight: 400;\">El estreno de la XII edici\u00f3n de la regata Puig Vela Cl\u00e0ssica ser\u00e1 dif\u00edcil de olvidar<\/span><b>, gracias a unas envidiables condiciones de navegaci\u00f3n <\/b><span style=\"font-weight: 400;\">y al acierto del comit\u00e9 de regatas con el recorrido elegido.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A las 13:00 horas se alzaba el tel\u00f3n con <\/span><b>la salida conjunta para las dos flotas de Cl\u00e1sicos,<\/b><span style=\"font-weight: 400;\"> y a continuaci\u00f3n part\u00edan los \u00c9poca Cangreja, \u00c9poca Bermudian y Big Boats en otras tres salidas. El recorrido establecido <\/span><b>ten\u00eda cuatro sectores,<\/b><span style=\"font-weight: 400;\"> partiendo frente el Port Ol\u00edmpic hacia una baliza de desmarque frente a la playa de la Barceloneta, una larga empopada hasta Masnou, regreso ci\u00f1endo hasta la baliza de la Barceloneta y un corto tramo final a favor de viento hasta la zona de salida. <\/span><b>Las cinco categor\u00edas han navegado id\u00e9ntico recorrido de 18 millas,<\/b><span style=\"font-weight: 400;\"> lo que ha facilitado el seguimiento de la prueba y ha ofrecido momentos espectaculares al irse mezclando las distintas flotas.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5317 size-full\" src=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2019\/07\/Los-E\u0301poca-Bermudian-Fjord-III-y-Cippino_I-jornada-regata-PVC-2019-scaled.jpeg\" alt=\"\" width=\"2500\" height=\"2575\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Si el recorrido ha sido bonito y exigente t\u00e9cnicamente, <\/span><b>las condiciones en el campo de regatas barcelon\u00e9s ser\u00e1n dif\u00edcilmente superables.<\/b><span style=\"font-weight: 400;\"> El viento t\u00e9rmico de Garb\u00ed soplaba con 16 nudos de intensidad en la salida, aumentando progresivamente hasta unos generosos 21-22 nudos. Pero afortunadamente para las esloras peque\u00f1as y medianas, el oleaje era m\u00ednimo para la fuerza del viento, evitando que las siete millas de ce\u00f1ida desde Masnou hasta la Barceloneta fueran un suplicio.\u00a0<\/span><\/p>\n<p><b>Marigold, Cippino, Guia, Argos y Moonbeam of Fife lideran la primera jornada de la clasificaci\u00f3n general\u00a0\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">El suspense en la competida categor\u00eda Cl\u00e1sicos 1 comenzaba tras la salida, <\/span><b>cuando los favoritos Guia y el Emeraude se adelantaban al disparo<\/b><span style=\"font-weight: 400;\"> y deb\u00edan regresar para partir de nuevo, iniciando dicha maniobra un poco tarde y acumulando un retraso considerable.\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5320\" src=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2019\/07\/Marigan_I-jornada-regata-PVC-2019.jpeg\" alt=\"\" width=\"2500\" height=\"1742\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Pero este contratiempo inicial les ha servido de acicate, comenzando una remontada que les ha permitido protagonizar la prueba. As\u00ed, el Emeraude cruzaba la meta primero y se clasificaba tercero tras la compensaci\u00f3n de tiempos, mientras el Guia era segundo en la llegada pero lograba la victoria tras la correcci\u00f3n de los handicaps. Entre ambos, en segunda posici\u00f3n, se colaba el Outlaw.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>En la flota de Cl\u00e1sicos 2<\/b><span style=\"font-weight: 400;\"> el Argos no ha tenido rival, dominando la clasificaci\u00f3n final con casi 6 minutos de ventaja sobre el Ojal\u00e1 II y ya m\u00e1s de 13 minutos con el Madrifa.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como si de un match race se tratara en \u00c9poca Bermudiano, el argentino Cippino y el uruguayo Fjord se han marcado y controlado sin tregua lo largo de las casi tres horas que han invertido en completar el recorrido. Separados en la meta por 17 segundos, el Cippino aumentaba el crono hasta los 33 segundos tras compensar los tiempos. El tercer pelda\u00f1o del podio ha sido para el Argyll.\u00a0<\/span><\/p>\n<p><b>Los tambi\u00e9n barcos de \u00c9poca, pero con aparejo Cangreja, han tenido como vencedor del d\u00eda al Marigold<\/b><span style=\"font-weight: 400;\"> tras contener al Veronique con un minuto y medio de ventaja, mientras el Marigan se clasificaba tercero.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5323\" src=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2019\/07\/Moonbeam-of-Fife-I-jornada-de-la-regata-Puig-Vela-Cla\u0300ssica.jpeg\" alt=\"\" width=\"1920\" height=\"1280\" \/><\/p>\n<p><b>Los cuatro Big Boats participantes en la XII regata Puig Vela Cl\u00e0ssica han tenido un claro dominador en el Moonbeam of Fife<\/b><span style=\"font-weight: 400;\">, que ha sabido aprovechar el fuerte viento de hoy para imponerse al Halloween con rotundidad, mientras el Black Swan y el Nordwind no finalizaban esta primera prueba.\u00a0<\/span><\/p>\n<p><b><br \/>\n<\/b><b>Resultados y clasificaciones al t\u00e9rmino de la primera jornada\u00a0<\/b><\/p>\n<p><b>Clasificaci\u00f3n de la jornada:<\/b><\/p>\n<p>&nbsp;<\/p>\n<p><b>En Cl\u00e1sicos 1<\/b><\/p>\n<li> Guia (Espa\u00f1a)<\/span><\/li>\n<li> Outlaw (Francia)<\/span><\/li>\n<li> Emeraude (Italia)<\/span><\/li>\n<p>&nbsp;<\/p>\n<p><b>En Cl\u00e1sicos 2\u00a0<\/b><\/p>\n<li>Argos (Espa\u00f1a)<\/span><\/li>\n<li>Ojala II (Reino Unido)<\/span><\/li>\n<li>Madrifra 2 (Italia)<\/span><\/li>\n<p><b>Big boats<\/b><\/p>\n<li>Moonbeam of Fife (Francia)<\/span><\/li>\n<li> Hallowe\u2019en (Irlanda)<\/span><\/li>\n<li> Black Swan (Reino Unido)<\/span><\/li>\n<p>&nbsp;<\/p>\n<p><b>Categor\u00eda \u00c9poca Bermudian<\/b><\/p>\n<li> Cippino (Argentina)<\/span><\/li>\n<li> Fjord III (Uruguay)<\/span><\/li>\n<li>Argyl (Reino Unido)<\/span><\/li>\n<p>&nbsp;<\/p>\n<p><b>Categor\u00eda \u00c9poca Cangreja<\/b><\/p>\n<li> Marigold (Reino Unido)<\/span><\/li>\n<li> Veronique (Espa\u00f1a)\u00a0<\/span><\/li>\n<li> Marigan (Espa\u00f1a)<\/span><\/li>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; El viento de garb\u00ed, y un recorrido junto a las playas han propiciado las envidiables condiciones de navegaci\u00f3n Turistas y barceloneses se han congregado en zonas emblem\u00e1ticas como el\u00a0Port Vell, las playas de la\u00a0Barceloneta\u00a0y\u00a0Sant Miquel para contemplar este espect\u00e1culo \u00fanico que une arte y deporte Guia, Argos, Moonbeam of Fife, Marigold y Cippino se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7037,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"class_list":["post-5328","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un mar y un viento de lujo en la primera jornada de la regata Puig Vela Cl\u00e0ssica - Puig Vela Cl\u00e0ssica Barcelona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/puigvelaclassica.com\/es\/un-mar-y-un-viento-de-lujo-en-la-primera-jornada-de-la-regata-puig-vela-classica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un mar y un viento de lujo en la primera jornada de la regata Puig Vela Cl\u00e0ssica - Puig Vela Cl\u00e0ssica Barcelona\" \/>\n<meta property=\"og:description\" content=\"&nbsp; El viento de garb\u00ed, y un recorrido junto a las playas han propiciado las envidiables condiciones de navegaci\u00f3n Turistas y barceloneses se han congregado en zonas emblem\u00e1ticas como el\u00a0Port Vell, las playas de la\u00a0Barceloneta\u00a0y\u00a0Sant Miquel para contemplar este espect\u00e1culo \u00fanico que une arte y deporte Guia, Argos, Moonbeam of Fife, Marigold y Cippino se [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/puigvelaclassica.com\/es\/un-mar-y-un-viento-de-lujo-en-la-primera-jornada-de-la-regata-puig-vela-classica\/\" \/>\n<meta property=\"og:site_name\" content=\"Puig Vela Cl\u00e0ssica Barcelona\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-11T18:11:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-20T13:37:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2019\/07\/Marigan_I-jornada-regata-PVC-2019-e1562868542838.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2462\" \/>\n\t<meta property=\"og:image:height\" content=\"1587\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"velaclassica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"velaclassica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/puigvelaclassica.com\/es\/un-mar-y-un-viento-de-lujo-en-la-primera-jornada-de-la-regata-puig-vela-classica\/\",\"url\":\"https:\/\/puigvelaclassica.com\/es\/un-mar-y-un-viento-de-lujo-en-la-primera-jornada-de-la-regata-puig-vela-classica\/\",\"name\":\"Un mar y un viento de lujo en la primera jornada de la regata Puig Vela Cl\u00e0ssica - Puig Vela Cl\u00e0ssica Barcelona\",\"isPartOf\":{\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/puigvelaclassica.com\/es\/un-mar-y-un-viento-de-lujo-en-la-primera-jornada-de-la-regata-puig-vela-classica\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/puigvelaclassica.com\/es\/un-mar-y-un-viento-de-lujo-en-la-primera-jornada-de-la-regata-puig-vela-classica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2019\/07\/Marigan_I-jornada-regata-PVC-2019-e1562868542838.jpeg\",\"datePublished\":\"2019-07-11T18:11:33+00:00\",\"dateModified\":\"2024-01-20T13:37:17+00:00\",\"author\":{\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/0f1f6cd6f23050a19e91a3003de34c7e\"},\"breadcrumb\":{\"@id\":\"https:\/\/puigvelaclassica.com\/es\/un-mar-y-un-viento-de-lujo-en-la-primera-jornada-de-la-regata-puig-vela-classica\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/puigvelaclassica.com\/es\/un-mar-y-un-viento-de-lujo-en-la-primera-jornada-de-la-regata-puig-vela-classica\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/puigvelaclassica.com\/es\/un-mar-y-un-viento-de-lujo-en-la-primera-jornada-de-la-regata-puig-vela-classica\/#primaryimage\",\"url\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2019\/07\/Marigan_I-jornada-regata-PVC-2019-e1562868542838.jpeg\",\"contentUrl\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2019\/07\/Marigan_I-jornada-regata-PVC-2019-e1562868542838.jpeg\",\"width\":2462,\"height\":1587},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/puigvelaclassica.com\/es\/un-mar-y-un-viento-de-lujo-en-la-primera-jornada-de-la-regata-puig-vela-classica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mail.puigvelaclasica.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un mar y un viento de lujo en la primera jornada de la regata Puig Vela Cl\u00e0ssica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#website\",\"url\":\"https:\/\/www.puigvelaclassicabarcelona.com\/\",\"name\":\"Puig Vela Cl\u00e0ssica Barcelona\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.puigvelaclassicabarcelona.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/0f1f6cd6f23050a19e91a3003de34c7e\",\"name\":\"velaclassica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/18a97ff0e5d67038bad233b79246a7f922424d224871d207487c88e471e664c2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/18a97ff0e5d67038bad233b79246a7f922424d224871d207487c88e471e664c2?s=96&d=mm&r=g\",\"caption\":\"velaclassica\"},\"sameAs\":[\"https:\/\/puigvelaclassica.com\/\"],\"url\":\"https:\/\/puigvelaclassica.com\/es\/author\/velaclassica\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un mar y un viento de lujo en la primera jornada de la regata Puig Vela Cl\u00e0ssica - Puig Vela Cl\u00e0ssica Barcelona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/puigvelaclassica.com\/es\/un-mar-y-un-viento-de-lujo-en-la-primera-jornada-de-la-regata-puig-vela-classica\/","og_locale":"es_ES","og_type":"article","og_title":"Un mar y un viento de lujo en la primera jornada de la regata Puig Vela Cl\u00e0ssica - Puig Vela Cl\u00e0ssica Barcelona","og_description":"&nbsp; El viento de garb\u00ed, y un recorrido junto a las playas han propiciado las envidiables condiciones de navegaci\u00f3n Turistas y barceloneses se han congregado en zonas emblem\u00e1ticas como el\u00a0Port Vell, las playas de la\u00a0Barceloneta\u00a0y\u00a0Sant Miquel para contemplar este espect\u00e1culo \u00fanico que une arte y deporte Guia, Argos, Moonbeam of Fife, Marigold y Cippino se [&hellip;]","og_url":"https:\/\/puigvelaclassica.com\/es\/un-mar-y-un-viento-de-lujo-en-la-primera-jornada-de-la-regata-puig-vela-classica\/","og_site_name":"Puig Vela Cl\u00e0ssica Barcelona","article_published_time":"2019-07-11T18:11:33+00:00","article_modified_time":"2024-01-20T13:37:17+00:00","og_image":[{"width":2462,"height":1587,"url":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2019\/07\/Marigan_I-jornada-regata-PVC-2019-e1562868542838.jpeg","type":"image\/jpeg"}],"author":"velaclassica","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"velaclassica","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/puigvelaclassica.com\/es\/un-mar-y-un-viento-de-lujo-en-la-primera-jornada-de-la-regata-puig-vela-classica\/","url":"https:\/\/puigvelaclassica.com\/es\/un-mar-y-un-viento-de-lujo-en-la-primera-jornada-de-la-regata-puig-vela-classica\/","name":"Un mar y un viento de lujo en la primera jornada de la regata Puig Vela Cl\u00e0ssica - Puig Vela Cl\u00e0ssica Barcelona","isPartOf":{"@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/puigvelaclassica.com\/es\/un-mar-y-un-viento-de-lujo-en-la-primera-jornada-de-la-regata-puig-vela-classica\/#primaryimage"},"image":{"@id":"https:\/\/puigvelaclassica.com\/es\/un-mar-y-un-viento-de-lujo-en-la-primera-jornada-de-la-regata-puig-vela-classica\/#primaryimage"},"thumbnailUrl":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2019\/07\/Marigan_I-jornada-regata-PVC-2019-e1562868542838.jpeg","datePublished":"2019-07-11T18:11:33+00:00","dateModified":"2024-01-20T13:37:17+00:00","author":{"@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/0f1f6cd6f23050a19e91a3003de34c7e"},"breadcrumb":{"@id":"https:\/\/puigvelaclassica.com\/es\/un-mar-y-un-viento-de-lujo-en-la-primera-jornada-de-la-regata-puig-vela-classica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/puigvelaclassica.com\/es\/un-mar-y-un-viento-de-lujo-en-la-primera-jornada-de-la-regata-puig-vela-classica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/puigvelaclassica.com\/es\/un-mar-y-un-viento-de-lujo-en-la-primera-jornada-de-la-regata-puig-vela-classica\/#primaryimage","url":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2019\/07\/Marigan_I-jornada-regata-PVC-2019-e1562868542838.jpeg","contentUrl":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/velaclassica\/uploads\/2019\/07\/Marigan_I-jornada-regata-PVC-2019-e1562868542838.jpeg","width":2462,"height":1587},{"@type":"BreadcrumbList","@id":"https:\/\/puigvelaclassica.com\/es\/un-mar-y-un-viento-de-lujo-en-la-primera-jornada-de-la-regata-puig-vela-classica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mail.puigvelaclasica.com\/es\/"},{"@type":"ListItem","position":2,"name":"Un mar y un viento de lujo en la primera jornada de la regata Puig Vela Cl\u00e0ssica"}]},{"@type":"WebSite","@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#website","url":"https:\/\/www.puigvelaclassicabarcelona.com\/","name":"Puig Vela Cl\u00e0ssica Barcelona","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.puigvelaclassicabarcelona.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/0f1f6cd6f23050a19e91a3003de34c7e","name":"velaclassica","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.puigvelaclassicabarcelona.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/18a97ff0e5d67038bad233b79246a7f922424d224871d207487c88e471e664c2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/18a97ff0e5d67038bad233b79246a7f922424d224871d207487c88e471e664c2?s=96&d=mm&r=g","caption":"velaclassica"},"sameAs":["https:\/\/puigvelaclassica.com\/"],"url":"https:\/\/puigvelaclassica.com\/es\/author\/velaclassica\/"}]}},"_links":{"self":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/posts\/5328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/comments?post=5328"}],"version-history":[{"count":2,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/posts\/5328\/revisions"}],"predecessor-version":[{"id":7049,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/posts\/5328\/revisions\/7049"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/media\/7037"}],"wp:attachment":[{"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/media?parent=5328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puigvelaclassica.com\/es\/wp-json\/wp\/v2\/categories?post=5328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}